{"id":6220,"date":"2026-01-12T00:00:00","date_gmt":"2026-01-12T00:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/passation-de-service-au-gwp-ao-une-transition-institutionnelle-sous-le-signe-de-la-continuite-et-de-la-confiance\/"},"modified":"2026-05-08T16:02:29","modified_gmt":"2026-05-08T15:02:29","slug":"passation-de-service-au-gwp-ao-une-transition-institutionnelle-sous-le-signe-de-la-continuite-et-de-la-confiance","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/news\/passation-de-service-au-gwp-ao-une-transition-institutionnelle-sous-le-signe-de-la-continuite-et-de-la-confiance\/","title":{"rendered":"Passation de service au GWP-AO : une transition institutionnelle sous le signe de la continuit\u00e9 et de la confiance"},"content":{"rendered":"<p>Plac\u00e9e sous la pr\u00e9sidence de <b>M. Abdoulaye SENE<\/b>, Pr\u00e9sident du GWP-AO, cette rencontre solennelle a r\u00e9uni de nombreux partenaires institutionnels et techniques, venus t\u00e9moigner de leur attachement \u00e0 la gouvernance r\u00e9gionale de l\u2019eau.<\/p>\n<p><b><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/passation_service_sidi_lamine1-1.jpg\" height=\"301\" width=\"640\"><\/b><\/p>\n<p><b>Une c\u00e9r\u00e9monie sobre mais hautement symbolique<\/b><\/p>\n<p>D\u2019une dur\u00e9e de trente minutes, la c\u00e9r\u00e9monie s\u2019est d\u00e9roul\u00e9e selon un protocole pr\u00e9cis :<\/p>\n<ul>\n<li>Apr\u00e8s l\u2019accueil des participants par <b>M. Hilaire Ilboudo<\/b>, le Pr\u00e9sident Abdoulaye SENE a ouvert officiellement la rencontre. Dans son allocution, il a rappel\u00e9 que cette passation de service illustre la <b>continuit\u00e9 institutionnelle<\/b> du GWP-AO et la volont\u00e9 de renforcer une gouvernance inclusive et durable des ressources en eau. Il a salu\u00e9 le travail accompli par M. Sidi Coulibaly durant l\u2019int\u00e9rim et souhait\u00e9 plein succ\u00e8s \u00e0 M. Amadou Lamine Ndiaye dans ses nouvelles fonctions.<\/li>\n<li><b>M. Sidi Coulibaly<\/b>, Secr\u00e9taire Ex\u00e9cutif par int\u00e9rim, a ensuite pris la parole pour rappeler les efforts de coordination et de consolidation men\u00e9s durant sa mission.<\/li>\n<li>Le nouveau Secr\u00e9taire Ex\u00e9cutif, <b>M. Amadou Lamine Ndiaye<\/b>, a pr\u00e9sent\u00e9 sa vision strat\u00e9gique pour le GWP-AO, ax\u00e9e sur la transparence, la gouvernance inclusive et l\u2019efficacit\u00e9 op\u00e9rationnelle.<\/li>\n<li>Un message de reconnaissance aux partenaires a \u00e9t\u00e9 d\u00e9livr\u00e9 par le ma\u00eetre de c\u00e9r\u00e9monie, rappelant leur r\u00f4le essentiel dans l\u2019accompagnement du GWP-AO.<\/li>\n<li><b>Dr Dibi Millogo<\/b>, Directeur Ex\u00e9cutif Adjoint de l\u2019Autorit\u00e9 du Bassin de la Volta (ABV), s\u2019est exprim\u00e9 au nom des partenaires. Il a salu\u00e9 la qualit\u00e9 du travail accompli par l\u2019\u00e9quipe int\u00e9rimaire, r\u00e9affirm\u00e9 la confiance des institutions partenaires dans le GWP-AO et exprim\u00e9 leur disponibilit\u00e9 \u00e0 accompagner le nouveau Secr\u00e9taire Ex\u00e9cutif dans la poursuite des objectifs communs.<\/li>\n<li>Le moment fort fut ensuite la <b>signature symbolique du rapport de passation<\/b>, acte qui consacre la transition officielle entre les deux responsables.<\/li>\n<li>La c\u00e9r\u00e9monie s\u2019est conclue par une allocution du Pr\u00e9sident Abdoulaye SENE, suivie d\u2019une photo de famille et d\u2019un cocktail convivial.<\/li>\n<\/ul>\n<p><b><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/passation_service_sidi_lamine4-1.jpg\" height=\"300\" width=\"640\"><\/b><\/p>\n<p><b>Une transition institutionnelle strat\u00e9gique<\/b><\/p>\n<p>La passation de service du 8 janvier 2025 marque une \u00e9tape importante pour le GWP-AO :<\/p>\n<ul>\n<li>Elle consacre la <b>fin de l\u2019int\u00e9rim assur\u00e9 par M. Sidi Coulibaly<\/b>, reconnu pour sa rigueur et son sens du consensus.<\/li>\n<li>Elle ouvre une nouvelle phase avec l\u2019arriv\u00e9e de <b>M. Amadou Lamine Ndiaye<\/b>, dont la mission sera de renforcer la gouvernance r\u00e9gionale et de consolider les partenariats strat\u00e9giques.<\/li>\n<li>Elle t\u00e9moigne de la <b>volont\u00e9 du GWP-AO de maintenir une gouvernance inclusive et transparente<\/b>, en phase avec les exigences des bailleurs internationaux et les besoins des \u00c9tats membres de la CEDEAO.<\/li>\n<\/ul>\n<p><b><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/passation_service_sidi_lamin-1.jpg\" height=\"480\" width=\"640\"><\/b><\/p>\n<p><b>Un signal fort aux partenaires<\/b><\/p>\n<p>La pr\u00e9sence de nombreux partenaires institutionnels et techniques \u00e0 cette c\u00e9r\u00e9monie illustre la confiance plac\u00e9e dans le GWP-AO.<\/p>\n<ul>\n<li>Les propos du Pr\u00e9sident ont soulign\u00e9 l\u2019importance de la coop\u00e9ration r\u00e9gionale pour relever les d\u00e9fis li\u00e9s \u00e0 la gestion durable des ressources en eau.<\/li>\n<li>L\u2019intervention de <b>Dr Dibi Millogo<\/b> au nom des partenaires a renforc\u00e9 ce message, en r\u00e9affirmant leur disponibilit\u00e9 \u00e0 soutenir le nouveau Secr\u00e9taire Ex\u00e9cutif et \u00e0 accompagner la continuit\u00e9 institutionnelle.<\/li>\n<li>La c\u00e9r\u00e9monie a ainsi mis en avant la dimension symbolique de la <b>transition harmonieuse<\/b>, gage de stabilit\u00e9 et de cr\u00e9dibilit\u00e9 aupr\u00e8s des acteurs r\u00e9gionaux et internationaux.<\/li>\n<\/ul>\n<p>La c\u00e9r\u00e9monie de passation de service entre <b>M. Sidi Coulibaly<\/b> et <b>M. Amadou Lamine Ndiaye<\/b>, sous la pr\u00e9sidence de <b>M. Abdoulaye SENE<\/b>, s\u2019inscrit dans une dynamique de consolidation et de renouvellement. Elle illustre la capacit\u00e9 du GWP-AO \u00e0 assurer une transition harmonieuse, tout en r\u00e9affirmant son engagement \u00e0 promouvoir une gouvernance efficace et participative des ressources en eau en Afrique de l\u2019Ouest.<\/p>\n<p>Avec cette nouvelle \u00e9tape, le GWP-AO se projette vers l\u2019avenir, fort de la confiance de ses partenaires et de la vision strat\u00e9gique de son nouveau Secr\u00e9taire Ex\u00e9cutif.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/passation_service_sidi_lamine2-1.jpg\" height=\"324\" width=\"640\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Ouagadougou, 8 janvier 2025 \u2013 Le si\u00e8ge du Partenariat Mondial de l\u2019Eau Afrique de l\u2019Ouest (GWP-AO) a abrit\u00e9 une c\u00e9r\u00e9monie officielle de passation de service entre le Secr\u00e9taire Ex\u00e9cutif par int\u00e9rim, M. Sidi Coulibaly, et le nouveau Secr\u00e9taire Ex\u00e9cutif, M. Amadou Lamine Ndiaye.<\/p>","protected":false},"author":1,"featured_media":10841,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":8,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/passation-de-service-au-gwp-ao--une-transition-institutionnelle-sous-le-signe-de-la-continuite-et-de-la-confiance\/"],"_last_date":["field_69d4d498acab3"],"last_date":["12\/01\/2026"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10841"],"_edit_last":["1"],"iawp_total_views":["8"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/passation_service_sidi_lamine.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/passation_service_sidi_lamine-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/passation_service_sidi_lamine-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/passation_service_sidi_lamine-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/passation_service_sidi_lamine-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/passation_service_sidi_lamine.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/passation_service_sidi_lamine.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/passation_service_sidi_lamine-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Ouagadougou, 8 janvier 2025 \u2013 Le si\u00e8ge du Partenariat Mondial de l\u2019Eau Afrique de l\u2019Ouest (GWP-AO) a abrit\u00e9 une c\u00e9r\u00e9monie officielle de passation de service entre le Secr\u00e9taire Ex\u00e9cutif par int\u00e9rim, M. Sidi Coulibaly, et le nouveau Secr\u00e9taire Ex\u00e9cutif, M. Amadou Lamine Ndiaye.","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/comments?post=6220"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6220\/revisions"}],"predecessor-version":[{"id":9440,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6220\/revisions\/9440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media\/10841"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media?parent=6220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/categories?post=6220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/tags?post=6220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}