{"id":6222,"date":"2025-12-22T00:00:00","date_gmt":"2025-12-22T00:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/mali-deux-stations-hydrometriques-installees-a-koula-pour-renforcer-lalerte-precoce-aux-inondations\/"},"modified":"2026-05-08T16:02:29","modified_gmt":"2026-05-08T15:02:29","slug":"mali-deux-stations-hydrometriques-installees-a-koula-pour-renforcer-lalerte-precoce-aux-inondations","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/news\/mali-deux-stations-hydrometriques-installees-a-koula-pour-renforcer-lalerte-precoce-aux-inondations\/","title":{"rendered":"Mali : Deux stations hydrom\u00e9triques install\u00e9es \u00e0 Koula pour renforcer l\u2019alerte pr\u00e9coce aux inondations"},"content":{"rendered":"<p>Cette initiative, port\u00e9e par la Direction Nationale de l\u2019Hydraulique (DNH) et le Partenariat National de l\u2019Eau du Mali (PNE-Mali), marque une avanc\u00e9e majeure dans la surveillance hydrom\u00e9t\u00e9orologique des cours d\u2019eau non p\u00e9rennes.<\/p>\n<p><b><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn-mali_equipement1-1.jpg\" height=\"830\" width=\"640\"><\/b><\/p>\n<p><b>Des stations intelligentes pour des donn\u00e9es en temps r\u00e9el<\/b><\/p>\n<p>Les \u00e9quipements install\u00e9s permettent d\u00e9sormais de mesurer :<\/p>\n<ul>\n<li>Le niveau d\u2019eau<\/li>\n<li>La pluviom\u00e9trie<\/li>\n<li>La temp\u00e9rature<\/li>\n<li>L\u2019humidit\u00e9 relative<\/li>\n<\/ul>\n<p>Gr\u00e2ce \u00e0 des microcontr\u00f4leurs connect\u00e9s \u00e0 des capteurs de pression et des cartes GSM, les donn\u00e9es sont transmises en temps r\u00e9el, avec une couverture assur\u00e9e pour deux ans via des puces data et forfaits internet.<\/p>\n<p><b>Une mission technique r\u00e9ussie<\/b><\/p>\n<p>La mission a mobilis\u00e9 une \u00e9quipe pluridisciplinaire compos\u00e9e d\u2019un ing\u00e9nieur hydraulicien, d\u2019un technicien hydrologue, d\u2019un repr\u00e9sentant du PNE-Mali et d\u2019un chauffeur. Les travaux ont inclus :<\/p>\n<ul>\n<li>L\u2019achat et la mise en \u0153uvre de mat\u00e9riaux de construction<\/li>\n<li>La confection d\u2019abris et de cl\u00f4tures grillag\u00e9es<\/li>\n<li>L\u2019implication de la main-d\u2019\u0153uvre locale<\/li>\n<li>L\u2019op\u00e9rationnalisation compl\u00e8te des stations<\/li>\n<\/ul>\n<p><b>Remise officielle et engagement institutionnel<\/b><\/p>\n<p>Le 16 d\u00e9cembre, une c\u00e9r\u00e9monie officielle de remise des \u00e9quipements \u00e0 la DNH et \u00e0 Mali M\u00e9t\u00e9o a \u00e9t\u00e9 organis\u00e9e, en pr\u00e9sence de la presse et des partenaires techniques. Ce moment symbolique a soulign\u00e9 l\u2019engagement du Mali \u00e0 renforcer ses capacit\u00e9s d\u2019alerte pr\u00e9coce face aux risques climatiques.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn-mali_equipement2-1.jpg\" height=\"853\" width=\"640\"><\/p>\n<p><b>Vers une cartographie intelligente du risque<\/b><\/p>\n<p>Cette installation concr\u00e9tise le livrable du produit 4 du projet AFCIA, valid\u00e9 en f\u00e9vrier 2025, et pr\u00e9pare l\u2019int\u00e9gration des donn\u00e9es hydrologiques au syst\u00e8me d\u2019alerte du Projet de Gestion des Risques Climatiques et des Inondations (PGRCI).<\/p>\n<p>Avec l\u2019appui du Climate Technology Centre &amp; Network (CTCN) et du Partenariat Mondial de l\u2019Eau en Afrique de l\u2019Ouest (GWP-AO), Koula devient un site pilote pour une gestion intelligente et inclusive du risque climatique.<\/p>\n<p><a title=\"Video installation.mp4\" href=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/assets\/legacy\/globalassets\/global\/gwp-waf_images\/2025\/ctcn_mali\/installation-equipement\/video-installation.mp4\/\">Video installation.mp4<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Koula, Mali \u2013 d\u00e9cembre 2025<br \/>\nDans le cadre du projet \u00ab\u202fCartographie en temps r\u00e9el du risque d\u2019inondation\u202f\u00bb financ\u00e9 par le Fonds d\u2019Adaptation via le programme AFCIA, deux stations automatiques multi-param\u00e8tres ont \u00e9t\u00e9 install\u00e9es avec succ\u00e8s dans la commune rurale de Koula, du 18 au 22 d\u00e9cembre 2025.<\/p>","protected":false},"author":1,"featured_media":10842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":6,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/mali--deux-stations-hydrometriques-installees-a-koula-pour-renforcer-lalerte-precoce-aux-inondations\/"],"_last_date":["field_69d4d498acab3"],"last_date":["22\/12\/2025"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10842"],"_edit_last":["1"],"enclosure":["https:\/\/gwpo-gwp.org\/assets\/legacy\/globalassets\/global\/gwp-waf_images\/2025\/ctcn_mali\/installation-equipement\/video-installation.mp4\n6360141\nvideo\/mp4\n"],"iawp_total_views":["6"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn-mali_equipement.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn-mali_equipement-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn-mali_equipement-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn-mali_equipement-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn-mali_equipement-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn-mali_equipement.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn-mali_equipement.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn-mali_equipement-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Koula, Mali \u2013 d\u00e9cembre 2025 Dans le cadre du projet \u00ab\u202fCartographie en temps r\u00e9el du risque d\u2019inondation\u202f\u00bb financ\u00e9 par le Fonds d\u2019Adaptation via le programme AFCIA, deux stations automatiques multi-param\u00e8tres ont \u00e9t\u00e9 install\u00e9es avec succ\u00e8s dans la commune rurale de Koula, du 18 au 22 d\u00e9cembre 2025.","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/comments?post=6222"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6222\/revisions"}],"predecessor-version":[{"id":9444,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6222\/revisions\/9444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media\/10842"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media?parent=6222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/categories?post=6222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/tags?post=6222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}