{"id":6233,"date":"2025-11-28T00:00:00","date_gmt":"2025-11-28T00:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/atelier-national-de-formation-des-relais-communautaires-et-eco-gardes-pour-la-gestion-durable-du-bassin-du-mono\/"},"modified":"2026-05-08T16:02:30","modified_gmt":"2026-05-08T15:02:30","slug":"atelier-national-de-formation-des-relais-communautaires-et-eco-gardes-pour-la-gestion-durable-du-bassin-du-mono","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/news\/atelier-national-de-formation-des-relais-communautaires-et-eco-gardes-pour-la-gestion-durable-du-bassin-du-mono\/","title":{"rendered":"Atelier national de formation des relais communautaires et \u00e9co-gardes pour la gestion durable du bassin du Mono"},"content":{"rendered":"<p>Cette activit\u00e9 s\u2019inscrit dans le cadre du <b>Projet IREE-Mono (2024-2028)<\/b>, mis en \u0153uvre par l\u2019<b>Autorit\u00e9 du Bassin du Mono (ABM)<\/b>, l\u2019<b>Observatoire du Sahara et du Sahel (OSS), UICN<\/b> et le <b>Partenariat Mondial de l\u2019Eau \u2013 Afrique de l\u2019Ouest (GWP-AO), et financ\u00e9 par le FEM<\/b>.<\/p>\n<p><b>L\u2019atelier visait \u00e0 r<\/b>enforcer les capacit\u00e9s des acteurs communautaires pour une <b>gestion int\u00e9gr\u00e9e des ressources naturelles<\/b>, en particulier de l\u2019eau, et promouvoir des pratiques durables dans la r\u00e9serve de biosph\u00e8re du Mono.<\/p>\n<p>L\u2019atelier a r\u00e9uni <b>34 participants<\/b>, dont des repr\u00e9sentants de l\u2019ABM, des associations communautaires de conservation de la biodiversit\u00e9 (ACCB), des services forestiers, du GWP-AO, du PNE B\u00e9nin, ainsi que des personnes ressources.<\/p>\n<p><b>Contenu et m\u00e9thodologie<\/b><\/p>\n<p>Pendant quatre jours, les participants ont suivi des modules interactifs portant sur :<\/p>\n<ul>\n<li><b>Communication et sensibilisation environnementale<\/b><\/li>\n<li><b>Gestion des conflits li\u00e9s aux ressources naturelles<\/b><\/li>\n<li><b>Am\u00e9nagement, conservation et suivi \u00e9cologique<\/b><\/li>\n<li><b>Surveillance et protection des aires prot\u00e9g\u00e9es<\/b><\/li>\n<li><b>R\u00e9glementation et \u00e9cotourisme<\/b><\/li>\n<\/ul>\n<p>L\u2019atelier a altern\u00e9 <b>expos\u00e9s, travaux de groupe, \u00e9tudes de cas et sorties de terrain<\/b>, favorisant un apprentissage participatif et pratique.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_ecogarde-1.jpg\" height=\"346\" width=\"640\"><\/p>\n<p><b>Exercice pratique innovant<\/b><\/p>\n<p>Un moment fort de la formation a \u00e9t\u00e9 l\u2019<b>exercice d\u2019application des outils de suivi \u00e9cologique<\/b>, incluant l\u2019utilisation de <b>drones<\/b> et de <b>cam\u00e9ras pi\u00e8ges<\/b> pour le suivi de la faune et la surveillance des zones sensibles. Cette approche technologique vise \u00e0 am\u00e9liorer la pr\u00e9cision des observations et \u00e0 renforcer la capacit\u00e9 des communaut\u00e9s \u00e0 prot\u00e9ger la biodiversit\u00e9.<\/p>\n<p><b>R\u00e9sultats attendus<\/b><\/p>\n<ul>\n<li>Une meilleure compr\u00e9hension des r\u00f4les et responsabilit\u00e9s des relais communautaires et \u00e9co-gardes.<\/li>\n<li>L\u2019\u00e9laboration d\u2019une <b>feuille de route post-formation<\/b> pour la valorisation des connaissances acquises.<\/li>\n<li>La remise d\u2019attestations aux participants.<\/li>\n<\/ul>\n<p>Cet atelier marque une \u00e9tape importante pour la <b>pr\u00e9servation des \u00e9cosyst\u00e8mes du bassin du Mono<\/b>, en renfor\u00e7ant la collaboration entre les communaut\u00e9s locales et les institutions r\u00e9gionales.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_ecogard-1.jpg\" height=\"300\" width=\"640\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Du 25 au 28 novembre 2025, s\u2019est tenu \u00e0 Grand-Popo (B\u00e9nin) l\u2019atelier national de formation des relais communautaires et des \u00e9co-gardes sur les techniques d\u2019information, de sensibilisation et de mobilisation des communaut\u00e9s locales dans la r\u00e9serve de biosph\u00e8re du Mono.<\/p>","protected":false},"author":1,"featured_media":10852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":15,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/atelier-national-de-formation-des-relais-communautaires-et-eco-gardes-pour-la-gestion-durable-du-bassin-du-mono\/"],"_last_date":["field_69d4d498acab3"],"last_date":["28\/11\/2025"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10852"],"_edit_last":["1"],"iawp_total_views":["15"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_ecogardes.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_ecogardes-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_ecogardes-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_ecogardes-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_ecogardes-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_ecogardes.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_ecogardes.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_ecogardes-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Du 25 au 28 novembre 2025, s\u2019est tenu \u00e0 Grand-Popo (B\u00e9nin) l\u2019atelier national de formation des relais communautaires et des \u00e9co-gardes sur les techniques d\u2019information, de sensibilisation et de mobilisation des communaut\u00e9s locales dans la r\u00e9serve de biosph\u00e8re du Mono.","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/comments?post=6233"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6233\/revisions"}],"predecessor-version":[{"id":9466,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6233\/revisions\/9466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media\/10852"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media?parent=6233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/categories?post=6233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/tags?post=6233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}