{"id":6240,"date":"2025-10-24T00:00:00","date_gmt":"2025-10-23T23:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/guinee-atelier-strategique-pour-accelerer-lacces-aux-financements-climatiques-via-le-fonds-vert-pour-le-climat-fvc-faire-progresser-lambition-africaine-en-matiere-de-financemen\/"},"modified":"2026-05-08T16:02:30","modified_gmt":"2026-05-08T15:02:30","slug":"guinee-atelier-strategique-pour-accelerer-lacces-aux-financements-climatiques-via-le-fonds-vert-pour-le-climat-fvc-faire-progresser-lambition-africaine-en-matiere-de-financemen","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/news\/guinee-atelier-strategique-pour-accelerer-lacces-aux-financements-climatiques-via-le-fonds-vert-pour-le-climat-fvc-faire-progresser-lambition-africaine-en-matiere-de-financemen\/","title":{"rendered":"Guin\u00e9e : Atelier strat\u00e9gique pour acc\u00e9l\u00e9rer l\u2019acc\u00e8s aux financements climatiques via le Fonds vert pour le climat (FVC) &#8211; Faire progresser l\u2019ambition africaine en mati\u00e8re de financement climatique avec l\u2019appui du GWP Afrique"},"content":{"rendered":"<p>Cette initiative s\u2019inscrit dans le cadre du projet multi-pays de pr\u00e9paration au FVC de l&#8217;UA-AIP mis en \u0153uvre dans quinze (15) pays africains, financ\u00e9 par le Fonds Vert Climat, et align\u00e9 sur l&#8217;ambition de l&#8217;Union africaine visant \u00e0 intensifier le financement climatique et la r\u00e9silience \u00e0 l\u2019\u00e9chelle continentale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/readiness_guinea1-1.jpg\" height=\"360\" width=\"640\">L\u2019Union africaine a fait du financement climatique une priorit\u00e9 strat\u00e9gique, reconnaissant que l\u2019acc\u00e8s aux ressources internationales\u2014en particulier via des m\u00e9canismes comme le FVC\u2014est essentiel pour atteindre les objectifs du continent en mati\u00e8re de s\u00e9curit\u00e9 hydrique, de protection de la biodiversit\u00e9 et d\u2019adaptation au changement climatique. Le projet multi-pays de pr\u00e9paration au GCF de l&#8217;UA-AIP incarne cette ambition en renfor\u00e7ant les capacit\u00e9s nationales et en acc\u00e9l\u00e9rant l&#8217;acc\u00e8s au financement climatique dans plusieurs pays africains, dont la Guin\u00e9e.<\/p>\n<p><b>Un atelier structurant pour des projets bancables<\/b><\/p>\n<p>Pendant trois jours et demi, pr\u00e8s de 30 participants issus d\u2019institutions publiques, du secteur priv\u00e9 et de la soci\u00e9t\u00e9 civile ont renforc\u00e9 leurs comp\u00e9tences pour :<\/p>\n<ul>\n<li>comprendre les crit\u00e8res d\u2019investissement du FVC et les exigences de soumission de projets.<\/li>\n<li>\u00e9laborer des justifications climatiques solides et des mod\u00e8les financiers coh\u00e9rents.<\/li>\n<li>int\u00e9grer les sauvegardes environnementales et sociales (SES), le genre et l\u2019inclusion.<\/li>\n<li>r\u00e9diger des notes conceptuelles adapt\u00e9es au contexte guin\u00e9en, pr\u00eates \u00e0 \u00eatre affin\u00e9es et soumises.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/readiness_guinea3-1.jpg\" height=\"360\" width=\"640\">Dans son allocution, le Repr\u00e9sentant du GWP Afrique, M. Sidi COULIBALY, Secr\u00e9taire Ex\u00e9cutif par int\u00e9rim de GWP-AO, a soulign\u00e9 que \u00ab <i>transformer les ambitions climatiques en investissements concrets est un processus exigeant, mais indispensable<\/i> \u00bb, insistant sur l\u2019importance d\u2019une \u00ab <i>approche technique rigoureuse, fond\u00e9e sur des outils de mod\u00e9lisation financi\u00e8re, des cadres de r\u00e9sultats align\u00e9s, et une th\u00e9orie du changement coh\u00e9rente<\/i> \u00bb.<\/p>\n<p>De son c\u00f4t\u00e9, le S.E\/AND-FVC, M. Mamadou Oury Barry, a rappel\u00e9 que \u00ab <i>la finance climatique ne doit pas \u00eatre un privil\u00e8ge pour quelques-uns, mais un droit pour tous les pays confront\u00e9s \u00e0 la crise climatique<\/i> \u00bb, appelant \u00e0 \u00ab <i>investir dans la formation des acteurs nationaux, am\u00e9liorer la qualit\u00e9 des donn\u00e9es climatiques, et promouvoir une approche inclusive impliquant les collectivit\u00e9s, les femmes, les jeunes et le secteur priv\u00e9<\/i> \u00bb.<\/p>\n<p><b>Une approche pratique et collaborative<\/b><\/p>\n<p>Anim\u00e9 par le GWP Afrique, l\u2019atelier a combin\u00e9 :<\/p>\n<ul>\n<li>des modules th\u00e9oriques sur l\u2019architecture du FVC, les crit\u00e8res d\u2019investissement, les m\u00e9canismes de cofinancement et les sauvegardes environnementales et sociales.<\/li>\n<li>des \u00e9tudes de cas et des exercices appliqu\u00e9s sur la structuration financi\u00e8re, la justification climatique, et l\u2019\u00e9laboration de la th\u00e9orie du changement.<\/li>\n<li>des travaux de groupe sur des projets concrets align\u00e9s sur les priorit\u00e9s nationales, incluant la mod\u00e9lisation financi\u00e8re, les plans d\u2019action genre et inclusion, et le cadre de r\u00e9sultats.<\/li>\n<\/ul>\n<p><b><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/readiness_guinea2-1.jpg\" height=\"360\" width=\"640\"><\/b><\/p>\n<p><b>Les prochaines \u00e9tapes<\/b><\/p>\n<p>Les prochaines \u00e9tapes comprennent la finalisation et la validation technique des notes conceptuelles, la structuration de l\u2019engagement avec le FVC pour la soumission formelle, et le renforcement de la coordination interinstitutionnelle autour du financement climatique. Outre cette formation au renforcement des capacit\u00e9s, le projet aidera \u00e9galement le pays \u00e0 obtenir l&#8217;accr\u00e9ditation des entit\u00e9s d\u00e9sign\u00e9es en tant qu&#8217;entit\u00e9s d&#8217;acc\u00e8s direct dans le cadre du FVC, \u00e0 \u00e9laborer une strat\u00e9gie d&#8217;engagement du secteur priv\u00e9, \u00e0 mettre au point un programme d&#8217;investissement dans la r\u00e9silience climatique dans le domaine de l&#8217;eau, et \u00e0 pr\u00e9parer des notes conceptuelles et le d\u00e9veloppement d&#8217;un pipeline pour le FVC et le financement par d&#8217;autres partenaires.<\/p>\n<p><b>La Guin\u00e9e dans l\u2019\u00e9cosyst\u00e8me africain du financement climatique<\/b><\/p>\n<p>Cet atelier marque une \u00e9tape cl\u00e9 dans la strat\u00e9gie nationale de la Guin\u00e9e pour acc\u00e9der aux financements climatiques. Il renforce le r\u00f4le de l\u2019AND comme catalyseur de projets inclusifs, ambitieux et techniquement solides\u2014tout en contribuant \u00e0 la vision continentale d\u2019une Afrique r\u00e9siliente et souveraine face aux d\u00e9fis climatiques.<\/p>","protected":false},"excerpt":{"rendered":"<p>Du 20 au 23 octobre 2025, l\u2019Autorit\u00e9 nationale d\u00e9sign\u00e9e (AND) de la Guin\u00e9e, avec l\u2019appui technique du GWP Afrique, a organis\u00e9 un atelier de renforcement des capacit\u00e9s ax\u00e9 sur l\u2019engagement strat\u00e9gique avec le Fonds vert pour le climat (FVC) et l\u2019\u00e9laboration de propositions de projets r\u00e9silients et bancables.<\/p>","protected":false},"author":1,"featured_media":10859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":51,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/guinee--atelier-strategique-pour-accelerer-lacces-aux-financements-climatiques-via-le-fonds-vert-pour-le-climat-fvc\/"],"_last_date":["field_69d4d498acab3"],"last_date":["24\/10\/2025"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10859"],"_edit_last":["1"],"iawp_total_views":["51"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/readiness_guinea.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/readiness_guinea-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/readiness_guinea-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/readiness_guinea-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/readiness_guinea-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/readiness_guinea.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/readiness_guinea.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/readiness_guinea-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Du 20 au 23 octobre 2025, l\u2019Autorit\u00e9 nationale d\u00e9sign\u00e9e (AND) de la Guin\u00e9e, avec l\u2019appui technique du GWP Afrique, a organis\u00e9 un atelier de renforcement des capacit\u00e9s ax\u00e9 sur l\u2019engagement strat\u00e9gique avec le Fonds vert pour le climat (FVC) et l\u2019\u00e9laboration de propositions de projets r\u00e9silients et bancables.","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/comments?post=6240"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6240\/revisions"}],"predecessor-version":[{"id":9480,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6240\/revisions\/9480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media\/10859"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media?parent=6240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/categories?post=6240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/tags?post=6240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}