{"id":6272,"date":"2025-02-07T00:00:00","date_gmt":"2025-02-07T00:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/afcia-mali-cartographie-du-risque-impacts-dinondation-et-mise-en-oeuvre-des-modeles-hydrologiques-dans-la-commune-de-koula-le-cercle-de-koulikoro\/"},"modified":"2026-05-08T16:02:32","modified_gmt":"2026-05-08T15:02:32","slug":"afcia-mali-cartographie-du-risque-impacts-dinondation-et-mise-en-oeuvre-des-modeles-hydrologiques-dans-la-commune-de-koula-le-cercle-de-koulikoro","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/news\/afcia-mali-cartographie-du-risque-impacts-dinondation-et-mise-en-oeuvre-des-modeles-hydrologiques-dans-la-commune-de-koula-le-cercle-de-koulikoro\/","title":{"rendered":"AFCIA Mali, cartographie du risque\/impacts d\u2019inondation et mise en \u0153uvre des mod\u00e8les hydrologiques dans la commune de Koula\/ le cercle de Koulikoro"},"content":{"rendered":"<p>L\u2019objectif de cette journ\u00e9e de rencontre est de renforcer le syst\u00e8me existant d\u2019alerte pr\u00e9coce du risque d\u2019inondation sur le territoire malien sur la base des pr\u00e9visions de pr\u00e9cipitations et des hauteurs d\u2019eau, avec l\u2019aide de la t\u00e9l\u00e9d\u00e9tection et de l\u2019apprentissage profond. Elle a permis d\u2019\u00e9changer sur la gestion des inondations et de l&#8217;eau au Mali, impliquant l&#8217;analyse de donn\u00e9es hydrom\u00e9t\u00e9orologiques, la mod\u00e9lisation hydrologique et la d\u00e9finition de seuils d&#8217;alerte. Les participants ont pass\u00e9 en revue la m\u00e9thodologie, les r\u00e9sultats pr\u00e9liminaires et les d\u00e9fis techniques li\u00e9s \u00e0 l&#8217;acquisition et \u00e0 l&#8217;installation d&#8217;\u00e9quipements de mesure. Les participants se sont pench\u00e9s sur la planification des activit\u00e9s restantes du projet, notamment l&#8217;installation d&#8217;une plateforme de pr\u00e9vision des inondations et la pr\u00e9paration d&#8217;un m\u00e9canisme de gestion post-projet.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn_mali-1.png\" height=\"300\" width=\"640\">Le Pr\u00e9sident du Partenariat National de l\u2019Eau (PNE) Mali, M. Navon CISSE, a remerci\u00e9 les partenaires techniques pour la mobilisation des ressources indispensables \u00e0 la r\u00e9alisation du projet.<\/p>\n<p>Le SE du GWP-AO a relev\u00e9 la grande mobilisation et l\u2019engagement de tous depuis le d\u00e9but du projet avec des r\u00e9sultats probants qui doivent \u00eatre p\u00e9rennis\u00e9s.<\/p>\n<p>Le repr\u00e9sentant du Directeur G\u00e9n\u00e9ral de l\u2019Agence pour l\u2019Environnement et le D\u00e9veloppement Durable (AEDD) du Mali a exprim\u00e9 sa satisfaction et sa gratuite pour les efforts d\u00e9ploy\u00e9s dans le cadre de la mise en \u0153uvre du projet AFCIA Mali.<\/p>\n<p><b>Des communications sur (1) l&#8217;analyse des donn\u00e9es et la d\u00e9finition des seuils d&#8217;alerte et de vigilance, (2) la mise en \u0153uvre de la cartographie du risque d\u2019inondation dans la commune de Koula, (3) <\/b>les mod\u00e8les hydrologiques du niveau r\u00e9gional au niveau local, (4) le Dossier d\u2019Appel d\u2019Offre (DAO).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn_mali_at21-1.png\" height=\"413\" width=\"640\">L&#8217;analyse des donn\u00e9es hydrom\u00e9t\u00e9orologiques dans le bassin versant du fleuve Niger, en particulier dans le cercle de Koulikoro et la commune de Koula \u00e9t\u00e9 pr\u00e9sent\u00e9e avec la m\u00e9thodologie utilis\u00e9e pour combler le manque de donn\u00e9es, incluant la domestication d&#8217;un mod\u00e8le global et l&#8217;analyse s\u00e9quentielle, combin\u00e9es aux r\u00e9sultats d&#8217;enqu\u00eates men\u00e9es dans 36 villages. L&#8217;objectif est de d\u00e9finir des seuils d&#8217;alerte et de vigilance pour les inondations fluviales, conform\u00e9ment aux exigences du projet.<\/p>\n<p>Un projet de pr\u00e9vision des inondations pour la commune de Koula, d\u00e9taillant la collecte et l&#8217;analyse des donn\u00e9es hydrologiques et m\u00e9t\u00e9orologiques a \u00e9t\u00e9 aussi pr\u00e9sent\u00e9 avec des explications sur l&#8217;utilisation de mod\u00e8les pour g\u00e9n\u00e9rer des d\u00e9bits simul\u00e9s, ainsi que la cartographie des risques pour 36 villages.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn_mali_at22-1.png\" height=\"408\" width=\"640\">Les participants ont aussi \u00e9chang\u00e9 sur le projet de cr\u00e9ation d&#8217;un outil d&#8217;aide \u00e0 la d\u00e9cision pour la pr\u00e9vision des inondations. L&#8217;importance de l&#8217;obtention des donn\u00e9es m\u00e9t\u00e9orologiques pr\u00e9cises a \u00e9t\u00e9 relev\u00e9 tout comme les d\u00e9fis budg\u00e9taires \u00e0 relever pour l&#8217;achat de mat\u00e9riel appropri\u00e9.<\/p>\n<p>Le rapport provisoire a \u00e9t\u00e9 valid\u00e9 sous r\u00e9serve de prise en compte des observations et amendements.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn_mali_at24-1.png\" height=\"300\" width=\"640\"><\/p>\n<p>La R\u00e9publique du Mali a obtenu un financement du Fonds d\u2019Adaptation \u00e0 travers le Programme Adaptation Fund Climate Innovation Accelerator (AFCIA) pour la mise en \u0153uvre du Projet \u00ab Cartographie en temps r\u00e9el du risque d\u2019inondation sur le territoire malien sur la base des pr\u00e9visions de pr\u00e9cipitations, de la t\u00e9l\u00e9d\u00e9tection et de l\u2019apprentissage profond \u00bb. Ce projet est mis en \u0153uvre avec l\u2019assistance technique du Partenariat Mondial de l\u2019Eau en Afrique de l\u2019Ouest (GWP-AO) sous la coordination du Climate Technology Centre &amp; Network (CTCN).<\/p>","protected":false},"excerpt":{"rendered":"<p>Les acteurs de mise en \u0153uvre du Projet \u00ab Cartographie en temps r\u00e9el du risque d\u2019inondation sur le territoire malien sur la base des pr\u00e9visions de pr\u00e9cipitations, de la t\u00e9l\u00e9d\u00e9tection et de l\u2019apprentissage profond \u00bb se sent r\u00e9unis le 06 f\u00e9vrier 2025 pour valider le rapport sur issue de la mission de cartographie du risque \/ impacts d\u2019inondation et mise en \u0153uvre des mod\u00e8les hydrologiques dans la commune de Koula dans le cercle de Koulikoro au Mali. La r\u00e9union a regroup\u00e9 les acteurs du Mali dans la salle de conf\u00e9rence de la Direction Nationale de l\u2019Hydraulique (DNH), les experts r\u00e9gionaux et du GWP-AO en ligne.<\/p>","protected":false},"author":1,"featured_media":10883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":7,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/afcia-mali-cartographie-du-risqueimpacts-dinondation-et-mise-en-uvre-des-modeles-hydrologiques-dans-la-commune-de-koula-le-cercle-de-koulikoro\/"],"_last_date":["field_69d4d498acab3"],"last_date":["07\/02\/2025"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10883"],"_edit_last":["1"],"iawp_total_views":["7"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn_mali_at2.png",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn_mali_at2-150x150.png",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn_mali_at2-300x145.png",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn_mali_at2-768x372.png",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn_mali_at2-1024x496.png",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn_mali_at2.png",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn_mali_at2.png",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/ctcn_mali_at2-18x9.png",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Les acteurs de mise en \u0153uvre du Projet \u00ab Cartographie en temps r\u00e9el du risque d\u2019inondation sur le territoire malien sur la base des pr\u00e9visions de pr\u00e9cipitations, de la t\u00e9l\u00e9d\u00e9tection et de l\u2019apprentissage profond \u00bb se sent r\u00e9unis le 06 f\u00e9vrier 2025 pour valider le rapport sur issue de la mission de cartographie du risque\u2026","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/comments?post=6272"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6272\/revisions"}],"predecessor-version":[{"id":9536,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6272\/revisions\/9536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media\/10883"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media?parent=6272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/categories?post=6272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/tags?post=6272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}