{"id":6280,"date":"2024-11-18T00:00:00","date_gmt":"2024-11-18T00:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/atelier-regional-de-formation-sur-les-exigences-de-loutil-daide-a-la-decision-oad\/"},"modified":"2026-05-08T16:02:32","modified_gmt":"2026-05-08T15:02:32","slug":"atelier-regional-de-formation-sur-les-exigences-de-loutil-daide-a-la-decision-oad","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/news\/atelier-regional-de-formation-sur-les-exigences-de-loutil-daide-a-la-decision-oad\/","title":{"rendered":"Atelier r\u00e9gional de formation sur les exigences de l\u2019outil d\u2019aide \u00e0 la d\u00e9cision (OAD)"},"content":{"rendered":"<p>L\u2019atelier r\u00e9gional s\u2019inscrit dans le cadre de l\u2019assistance technique du Centre du Programme des Nations Unies pour l\u2019Environnement sur l\u2019eau et l\u2019environnement (DHI) \u00e0 la mise en \u0153uvre du projet \u00ab&nbsp;Inverser les tendances de la D\u00e9gradation des Ecosyst\u00e8mes et des ressources en eaux dans le Bassin de la Volta (REWarD \u2013 Volta River Basin)&nbsp;\u00bb. Le projet, financ\u00e9 par le Fonds pour l\u2019Environnement Mondial (FEM), vise entre autres \u00e0 mettre en place un Syst\u00e8me d\u2019Aide \u00e0 la D\u00e9cision (SAD) pour la planification et la gestion des ressources en eau, un Syst\u00e8me d\u2019Alerte Pr\u00e9coce \u00e0 la S\u00e9cheresse (SAPS) et le renforcement des capacit\u00e9s des parties prenantes du bassin de la Volta. Il est ex\u00e9cut\u00e9 par l\u2019ABV et le GWP-AO puis mis en \u0153uvre par le Programme des Nations Unies pour l\u2019Environnement (PNUE) et l\u2019Union Internationale pour la Conservation de la Nature (UICN).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_room-view-1.jpg\" height=\"301\" width=\"639\">La c\u00e9r\u00e9monie d\u2019ouverture de l\u2019atelier a \u00e9t\u00e9 pr\u00e9sid\u00e9e par Monsieur Antoine KOFFI DJAA, Directeur Adjoint de Cabinet du Minist\u00e8re des Eaux et For\u00eats de la R\u00e9publique de la C\u00f4te d\u2019Ivoire en pr\u00e9sence du Directeur Ex\u00e9cutif Adjoint de l\u2019ABV, Monsieur Dibi MILLOGO, Monsieur Armand HOUANYE, Secr\u00e9taire Ex\u00e9cutif du GWP-AO, et M. Monsieur Wonnan Eug\u00e8ne YEO, Directeur G\u00e9n\u00e9ral des ressources en eau de la R\u00e9publique de la C\u00f4te d\u2019Ivoire.<\/p>\n<p>L\u2019atelier a r\u00e9uni une trentaine de participants en pr\u00e9sentiel et une quinzaine de participants en ligne venus de l\u2019Observatoire du Bassin de la Volta, des directions techniques en charge de l\u2019Eau, de l\u2019hydrologie, de la m\u00e9t\u00e9orologie, de l\u2019agriculture, de l\u2019environnement, de la coop\u00e9ration internationale, etc. des six pays du bassin de la Volta. Les \u00e9changes ont port\u00e9 sur divers aspects techniques et organisationnels, notamment l&#8217;utilisation d&#8217;outils de visualisation de donn\u00e9es, la gestion de bases de donn\u00e9es, et l&#8217;importance de la collecte et de l&#8217;analyse de donn\u00e9es hydrologiques, climatiques et d&#8217;usage de l&#8217;eau.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_salle-1-1.jpg\" height=\"300\" width=\"640\">Globalement, l\u2019atelier a permis de d\u00e9finir et de discuter des exigences techniques et des besoins des utilisateurs et renforcer les capacit\u00e9s des participants en vue de leur participation effective au d\u00e9veloppement et \u00e0 la mise en \u0153uvre de l&#8217;OAD dans le cadre du projet REWarD. Il a abord\u00e9 la conception de la base de connaissances, du syst\u00e8me d&#8217;alerte pr\u00e9coce \u00e0 la s\u00e9cheresse (SAPS), et de l&#8217;outil de planification des ressources en eau.<\/p>\n<p>Les participants se sont accord\u00e9s sur le contenu et les fonctionnalit\u00e9s des outils en fonction des attentes des b\u00e9n\u00e9ficiaires et utilisateurs afin de s\u2019assurer que le futur OAD r\u00e9ponde \u00e0 leurs attentes.<\/p>\n<p>Des connaissances pour une compr\u00e9hension claire des composantes cl\u00e9s de l&#8217;OAD, y compris la base de connaissances, le syst\u00e8me d\u2019alerte pr\u00e9coce \u00e0 la s\u00e9cheresse et l\u2019outil de planification des ressources en eau ont \u00e9t\u00e9 pr\u00e9sent\u00e9es.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_salleen-1.jpg\" height=\"305\" width=\"640\">Les participants ont \u00e9t\u00e9 renforc\u00e9s sur le partage d&#8217;informations et de connaissances sur les ressources en eau \u00e0 l&#8217;aide d&#8217;une version initiale de l&#8217;interface Web de la base de connaissances OAD, comprenant des donn\u00e9es de station (par exemple, des stations de jaugeage), des donn\u00e9es statiques (par exemple, la capacit\u00e9 des r\u00e9servoirs) et les derni\u00e8res donn\u00e9es op\u00e9rationnelles des jeux de donn\u00e9es d&#8217;observation de la Terre (par exemple, les pr\u00e9cipitations par satellite).<\/p>\n<p>L\u2019atelier a permis de discuter des donn\u00e9es n\u00e9cessaires pour le d\u00e9veloppement de l\u2019AOD ainsi que les difficult\u00e9s d\u2019acc\u00e8s pour l\u2019obtention des donn\u00e9es m\u00e9t\u00e9orologiques malgr\u00e9 que la charte de l\u2019eau du bassin de la volta fait obligation aux pays de partager leurs donn\u00e9es pour le bien des populations \u00e0 l\u2019\u00e9chelle du dit bassin.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_togoview-1.jpg\" height=\"300\" width=\"640\">En termes de prochaines \u00e9tapes, tous les pays doivent envoyer leurs commentaires sur le choix du mod\u00e8le hydrologique dans un d\u00e9lai d&#8217;une semaine. Le Consultant DHI doit d\u00e9velopper le mod\u00e8le de ressources en eau pour l&#8217;outil de planification d&#8217;ici juin 2025, organiser un atelier pour d\u00e9finir les indicateurs, sc\u00e9narios et \u00e9tudes de cas pour l&#8217;outil de planification, travailler sur un plan de durabilit\u00e9 pour l&#8217;outil de d\u00e9cision et mettre \u00e0 jour le rapport sur l&#8217;inventaire des donn\u00e9es existantes avec les nouvelles informations fournies lors de l&#8217;atelier. Il doit pr\u00e9voir de fournir des formations sur l&#8217;utilisation et l&#8217;exploitation du syst\u00e8me d&#8217;alerte pr\u00e9coce de s\u00e9cheresse une fois d\u00e9velopp\u00e9 et d\u00e9velopper des manuels d&#8217;utilisation en anglais et en fran\u00e7ais pour l&#8217;outil de d\u00e9cision.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_vue-1.jpg\" height=\"300\" width=\"640\">Quant \u00e0 l\u2019Autorit\u00e9 de Bassin de la Volta, elle doit d\u00e9terminer des sites pilotes pour les consultations communautaires sur le syst\u00e8me d&#8217;alerte pr\u00e9coce de s\u00e9cheresse, mettre en place un comit\u00e9 technique pour examiner en d\u00e9tail le choix du mod\u00e8le hydrologique. L\u2019ABV doit \u00e9laborer une strat\u00e9gie pour la prise en charge de l&#8217;outil apr\u00e8s les 5 ans du projet et organiser la prochaine r\u00e9union du comit\u00e9 de pilotage pour pr\u00e9senter les avanc\u00e9es du projet.<\/p>\n<p>Chaque pays du bassin de la Volta doit identifier une personne focale pour le suivi du projet au niveau national.<\/p>","protected":false},"excerpt":{"rendered":"<p>Abidjan, la capitale ivoirienne a abrit\u00e9 les 15 et 16 novembre 2024 un atelier r\u00e9gional de formation sur les exigences de l\u2019outil d\u2019aide \u00e0 la d\u00e9cision pour une planification et une gestion durable des ressources en eau dans le bassin de la Volta.<\/p>","protected":false},"author":1,"featured_media":10889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":11,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/atelier-regional-de-formation-sur-les-exigences-de-loutil-daide-a-la-decision-oad\/"],"_last_date":["field_69d4d498acab3"],"last_date":["18\/11\/2024"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10889"],"_edit_last":["1"],"iawp_total_views":["11"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_hightable.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_hightable-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_hightable-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_hightable-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_hightable-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_hightable.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_hightable.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_hightable-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Abidjan, la capitale ivoirienne a abrit\u00e9 les 15 et 16 novembre 2024 un atelier r\u00e9gional de formation sur les exigences de l\u2019outil d\u2019aide \u00e0 la d\u00e9cision pour une planification et une gestion durable des ressources en eau dans le bassin de la Volta.","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/comments?post=6280"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6280\/revisions"}],"predecessor-version":[{"id":9550,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6280\/revisions\/9550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media\/10889"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media?parent=6280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/categories?post=6280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/tags?post=6280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}