{"id":6287,"date":"2024-07-16T00:00:00","date_gmt":"2024-07-15T23:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/cedeao-suivi-de-la-mise-en-oeuvre-de-la-gire-resultats-des-rencontres-statutaires-dabuja\/"},"modified":"2026-05-08T16:02:32","modified_gmt":"2026-05-08T15:02:32","slug":"cedeao-suivi-de-la-mise-en-oeuvre-de-la-gire-resultats-des-rencontres-statutaires-dabuja","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/news\/cedeao-suivi-de-la-mise-en-oeuvre-de-la-gire-resultats-des-rencontres-statutaires-dabuja\/","title":{"rendered":"CEDEAO, suivi de la mise en \u0153uvre de la GIRE, r\u00e9sultats des rencontres statutaires d\u2019Abuja"},"content":{"rendered":"<p class=\"Default\">La 5<sup>\u00e8me<\/sup> Session Ordinaire du Comit\u00e9 Minist\u00e9riel de Suivi (CMS) de la Gestion Int\u00e9gr\u00e9e des Ressources en Eau (GIRE) en Afrique de l\u2019Ouest s\u2019est tenue le 28 juin 2024 \u00e0 Abuja au Nigeria. Cette rencontre a \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9e par la 11<sup>\u00e8me<\/sup> session ordinaire du Comit\u00e9 Technique des Experts (CTE) du 25 au 27 juin 2024.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/cms_salle-1.jpg\" height=\"571\" width=\"1180\">L\u2019objectif global de ces r\u00e9unions statutaires du Cadre Permanent de Coordination et de Suivi de la GIRE en Afrique de l\u2019Ouest (CPCS) est de r<b>evisiter le processus r\u00e9gional de GIRE en Afrique de l\u2019Ouest et d\u00e9gager des perspectives de travail porteuses, <\/b>prenant en compte les \u00e9volutions enregistr\u00e9es au niveau de la r\u00e9gion en mati\u00e8re de gestion des ressources en eau depuis 2015.<\/p>\n<p>A l\u2019issue de ces rencontres <a href=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/assets\/legacy\/globalassets\/global\/gwp-waf_files\/2024\/cedeao\/fr-resolution-13_initiative-dreve.pdf\/\">des r\u00e9solutions<\/a> ont \u00e9t\u00e9 prises, un <a href=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/assets\/legacy\/globalassets\/global\/gwp-waf_files\/2024\/cedeao\/communique-final-cms5.pdf\/\">communiqu\u00e9 final <\/a>\u00e9mit avec le <a href=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/assets\/legacy\/globalassets\/global\/gwp-waf_files\/2024\/cedeao\/rapport-cte11.pdf\/\">rapport de la rencontre des experts<\/a>.<\/p>\n<p class=\"Default\">Le processus de Gestion Int\u00e9gr\u00e9e des Ressources en Eau (GIRE) en Afrique de l\u2019Ouest est n\u00e9 de la <b>Conf\u00e9rence Minist\u00e9rielle Ouest Africaine <\/b>sur la gestion int\u00e9gr\u00e9e des ressources en eau tenue \u00e0 Ouagadougou du 3 au 5 mars 1998.<\/p>\n<p class=\"Default\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/cms_roomtotal-1.jpg\" height=\"306\" width=\"640\">Au cours de cette Conf\u00e9rence, les 16 pays de la CEDEAO d\u2019alors se sont r\u00e9solument engag\u00e9s \u00e0 passer d\u2019une gestion des ressources en eau sectorielle et technocratique \u00e0 une gestion int\u00e9gr\u00e9e et participative, conform\u00e9ment aux principes adopt\u00e9s par la Conf\u00e9rence pr\u00e9paratoire de Dublin en janvier 1992 et ent\u00e9rin\u00e9e par la CNUED de Rio de Janeiro en juin 1992.<\/p>\n<p>L\u2019application des recommandations de cette Conf\u00e9rence a notamment abouti \u00e0 l\u2019adoption du Plan d\u2019Action R\u00e9gional de Gestion Int\u00e9gr\u00e9e des Ressources en Eau de l\u2019Afrique de l\u2019Ouest (PARGIRE-AO) par la Conf\u00e9rence des Chefs d\u2019Etat et de Gouvernement de la CEDEAO en d\u00e9cembre 2000 et \u00e0 la cr\u00e9ation d\u2019un <b>Cadre Permanent de Coordination et de Suivi (CPCS) <\/b>de la GIRE en Afrique de l\u2019Ouest par d\u00e9cision de la Conf\u00e9rence des Chefs d\u2019Etat et de Gouvernement de la CEDEAO en d\u00e9cembre 2001.<\/p>\n<p class=\"Default\"><b>Le Comit\u00e9 Minist\u00e9riel de Suivi (CMS) : <\/b>le CMS est compos\u00e9 des ministres en charge des ressources en eau des 15 Etats membres de la CEDEAO. Il constitue l\u2019organe de d\u00e9cision et d\u2019orientation du CPCS. Il se r\u00e9unit une fois tous les deux (02) ans ;<\/p>\n<p class=\"Default\"><b>Le Comit\u00e9 Technique des Experts (CTE) : <\/b>est compos\u00e9 des points focaux qui sont les experts des ressources en eau repr\u00e9sentant d\u2019une part les Etats membres, et d\u2019autre part les organisations de bassin de l\u2019Afrique de l\u2019Ouest.<\/p>\n<p>Le CTE a pour mission d\u2019assister le CMS dans son r\u00f4le d\u2019orientation et de pilotage du CPCS.<\/p>\n<p>Le GWP-AO repr\u00e9sent\u00e9 par son Responsable \u00e0 la Communication et la Gestion des Connaissances, M. Sidi COULIBALY, a pris part \u00e0 ces rencontres d\u2019Abuja.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/cms_room-1.jpg\" height=\"317\" width=\"640\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/cms_room_part-1.jpg\" height=\"316\" width=\"640\"><\/p>","protected":false},"excerpt":{"rendered":"<p>La 5\u00e8me Session Ordinaire du Comit\u00e9 Minist\u00e9riel de Suivi (CMS) de la Gestion Int\u00e9gr\u00e9e des Ressources en Eau (GIRE) en Afrique de l\u2019Ouest s\u2019est tenue le 28 juin 2024 \u00e0 Abuja au Nigeria. Cette rencontre a \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9e par la 11\u00e8me session ordinaire du Comit\u00e9 Technique des Experts (CTE) du 25 au 27 juin 2024.<\/p>","protected":false},"author":1,"featured_media":10895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":25,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/cedeao-suivi-de-la-mise-en-uvre-de-la-gire-resultats-des-rencontres-statutaires-dabuja\/"],"_last_date":["field_69d4d498acab3"],"last_date":["16\/07\/2024"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10895"],"_edit_last":["1"],"iawp_total_views":["25"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/cms_groupe_pic.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/cms_groupe_pic-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/cms_groupe_pic-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/cms_groupe_pic-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/cms_groupe_pic-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/cms_groupe_pic.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/cms_groupe_pic.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/cms_groupe_pic-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"La 5\u00e8me Session Ordinaire du Comit\u00e9 Minist\u00e9riel de Suivi (CMS) de la Gestion Int\u00e9gr\u00e9e des Ressources en Eau (GIRE) en Afrique de l\u2019Ouest s\u2019est tenue le 28 juin 2024 \u00e0 Abuja au Nigeria. Cette rencontre a \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9e par la 11\u00e8me session ordinaire du Comit\u00e9 Technique des Experts (CTE) du 25 au 27 juin 2024.","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/comments?post=6287"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6287\/revisions"}],"predecessor-version":[{"id":9562,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6287\/revisions\/9562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media\/10895"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media?parent=6287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/categories?post=6287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/tags?post=6287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}