{"id":6325,"date":"2023-11-08T00:00:00","date_gmt":"2023-11-08T00:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/etude-prospective-sur-la-mise-en-oeuvre-des-odd-lies-a-leau-et-a-lassainissement-et-a-la-politique-commune-damelioration-de-lenvironnement-de-luemoa\/"},"modified":"2026-05-08T16:02:35","modified_gmt":"2026-05-08T15:02:35","slug":"etude-prospective-sur-la-mise-en-oeuvre-des-odd-lies-a-leau-et-a-lassainissement-et-a-la-politique-commune-damelioration-de-lenvironnement-de-luemoa","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/news\/etude-prospective-sur-la-mise-en-oeuvre-des-odd-lies-a-leau-et-a-lassainissement-et-a-la-politique-commune-damelioration-de-lenvironnement-de-luemoa\/","title":{"rendered":"Etude prospective sur la mise en \u0153uvre des ODD li\u00e9s \u00e0 l&#8217;eau et \u00e0 l&#8217;assainissement et \u00e0 la Politique Commune d\u2019Am\u00e9lioration de l\u2019Environnement de l\u2019UEMOA"},"content":{"rendered":"<p>L\u2019atelier a permis d\u2019examiner et de valider le rapport provisoire de l\u2019\u00e9tude.<\/p>\n<p>Ainsi, la situation de mise en \u0153uvre de l\u2019ODD 6 dans les Etats membres, le bilan de la d\u00e9cennie de mise en \u0153uvre de la PCAE dans le domaine de l\u2019eau et de l\u2019assainissement, le m\u00e9canisme de suivi des diff\u00e9rents indicateurs&nbsp;de l\u2019ODD 6&nbsp;ainsi que le plan d\u2019action au niveau r\u00e9gional ont \u00e9t\u00e9 examin\u00e9s.<\/p>\n<p>La rencontre a regroup\u00e9 les Experts des Etats membres en charge de la mise en \u0153uvre des ODD li\u00e9s \u00e0 l&#8217;eau et \u00e0 l&#8217;assainissement et des questions de planification desdits ODD, les repr\u00e9sentants de la Commission de l\u2019UEMOA et du<a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwj66-W0-Y2AAxUrTkEAHaUoDugQFnoECCAQAQ&amp;url=https%3A%2F%2Fwww.facebook.com%2Fgwpao%2F%3Flocale%3Dfr_FR&amp;usg=AOvVaw2qv1zukyRqtQtTzad2sCyL&amp;opi=89978449\"> Global Water Partnership Afrique de l\u2019Ouest (GWP-AO) <\/a>et les Experts du Groupement EAR-EMERGENCY\/LUCIOLE Conseils.<\/p>\n<p>Selon <b>Monsieur Kako NUBUKPO<\/b>, Commissaire charg\u00e9 du D\u00e9partement de l\u2019Agriculture, des Ressources en Eau et de l\u2019Environnement (DAREN) de la Commission de l\u2019UEMOA, \u00ab&nbsp;<i>la Commission de l\u2019UEMOA a \u00e9labor\u00e9 en 2020 puis en 2021, deux rapports r\u00e9gionaux de suivi des Plans Nationaux de D\u00e9veloppement et des Strat\u00e9gies de R\u00e9duction de la Pauvret\u00e9 (PND\/DSRP) ax\u00e9 sur les Objectifs de D\u00e9veloppement Durable. Bien que ces rapports comportent des informations sur la mise en \u0153uvre des ODD de mani\u00e8re g\u00e9n\u00e9rale, il s\u2019est av\u00e9r\u00e9 n\u00e9cessaire, pour la Commission, de faire un point sp\u00e9cifique sur la situation de l\u2019ODD 6<\/i>&nbsp;\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/canal_uemoa_ok-2.jpg\" height=\"301\" width=\"640\"><\/p>\n<p><b>Sur la situation de mise en \u0153uvre de l\u2019ODD 6 dans les Etats membres&nbsp;:<\/b><\/p>\n<ul>\n<li><b>pour l\u2019eau et l\u2019assainissement&nbsp;<\/b>: des efforts non n\u00e9gligeables men\u00e9s par les Etats ont abouti \u00e0 une croissance lente de 1% \/ an pour le taux d\u2019acc\u00e8s \u00e0 l\u2019eau potable et de 0,8% \/ an pour le taux d\u2019acc\u00e8s \u00e0 l\u2019assainissement am\u00e9lior\u00e9 des eaux us\u00e9es et excr\u00e9tas. Au 31 d\u00e9cembre 2022, 92% de la population urbaine et 72% des populations rurales de l\u2019espace UEMOA ont acc\u00e8s \u00e0 un service d\u2019eau potable g\u00e9r\u00e9 en toute s\u00e9curit\u00e9. Aussi, 72% de la population urbaine et 30% des populations rurales ont acc\u00e8s \u00e0 un service d\u2019assainissement am\u00e9lior\u00e9. A ce rythme, aucun Etat membre de l\u2019UEMOA n\u2019atteindra les cibles de l\u2019ODD 6 (Eau potable et Assainissement) en 2030&nbsp;;<\/li>\n<li><b>pour la GIRE<\/b>&nbsp;: une performance globalement moyenne dans l\u2019ensemble de l\u2019espace UEMOA, si l\u2019on consid\u00e8re toutes les dimensions retenues dans la mise en \u0153uvre de la GIRE dans les Etats membres. Des disparit\u00e9s sont constat\u00e9es au niveau de la mise en \u0153uvre de la GIRE dans les Etats faisant ressortir deux classes selon les performances&nbsp;: les Etats relativement avanc\u00e9s dans le processus et les Etats faiblement avanc\u00e9s. D\u2019une mani\u00e8re g\u00e9n\u00e9rale il faut noter que des d\u00e9fis importants sont encore \u00e0 relever dans l\u2019ensemble des Etats membres au risque que les cibles de l\u2019ODD 6 ne soient pas atteints \u00e0 l\u2019horizon 2030.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/fontaine_uemoa_ok-1-1.jpg\" height=\"427\" width=\"640\"><b>S\u2019agissant de la PCAE dans le domaine de l\u2019eau et de l\u2019assainissement<\/b>, il faut noter que ladite politique a \u00e9t\u00e9 mise en \u0153uvre \u00e0 travers trois (03) programmes structurants impl\u00e9ment\u00e9s dans les Etats membres dans les domaines de l\u2019eau potable et de l\u2019assainissement. Il s\u2019agit du Programme d\u2019Hydraulique Villageoise (PHV), du Programme BID-UEMOA d\u2019Hydraulique et d\u2019Assainissement en Milieu Rural et du Programme d\u2019Am\u00e9nagement Hydraulique Multi-usages (PAHM). D\u2019un montant global de 110,&nbsp;406 milliards FCFA, la mise en \u0153uvre de ces programmes a permis d\u2019am\u00e9liorer les taux d\u2019acc\u00e8s \u00e0 l\u2019eau potable et \u00e0 l\u2019assainissement respectivement de 6,0% et de 1,7%.<\/p>\n<p><b>Sur les m\u00e9canismes de suivi et \u00e9valuation de l\u2019ODD 6, <\/b>le dispositif de pilotage du m\u00e9canisme de suivi des interventions de l\u2019UEMOA s\u2019appuie sur un comit\u00e9 gouvernemental de supervision, un comit\u00e9 technique de coordination du suivi des ODD et quatre (04) groupes th\u00e9matiques prenant en compte l\u2019ensemble des 17 ODD. L\u2019atelier a relev\u00e9 entre autres, la n\u00e9cessit\u00e9 de d\u00e9crire les m\u00e9canismes de suivi-\u00e9valuation existant de l\u2019ODD6 au niveau mondial, africain, r\u00e9gional et national (pour chaque Etat membre), la n\u00e9cessit\u00e9 de relever les points forts et les points faibles des m\u00e9canismes de suivi-\u00e9valuation de l\u2019ODD6 qui permettront de mettre en exergue les goulots d\u2019\u00e9tranglement ainsi que les engagements non tenus par les Etats membres ainsi que le besoin de renforcement des capacit\u00e9s, d\u2019appui technique et financier des m\u00e9canismes nationaux de suivi-\u00e9valuation de l\u2019ODD6.<\/p>\n<p><b><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/uemoa_carte_ok-1.jpg\" height=\"571\" width=\"1180\">Sur le Plan d\u2019actions r\u00e9gional de l\u2019UEMOA en appui aux Etats membres, <\/b>un plan d\u2019actions r\u00e9gional, formul\u00e9 en quatre (04) programmes pour un montant global de 1&nbsp;321,76 milliards de francs CFA a \u00e9t\u00e9 formul\u00e9. Il s\u2019agit du programme 1&nbsp;: Acc\u00e8s aux services publics d\u2019eau potable g\u00e9r\u00e9s en toute s\u00e9curit\u00e9, du programme 2&nbsp;: Acc\u00e8s aux services publics d\u2019assainissement am\u00e9lior\u00e9s, du programme 3&nbsp;: Op\u00e9rationnalisation de la Gestion Int\u00e9gr\u00e9e des Ressources en Eau et du programme 4&nbsp;: Accompagnement des Groupes th\u00e9matiques en charge du suivi-\u00e9valuation des indicateurs li\u00e9s aux interventions de l\u2019UEMOA. A ce niveau, l\u2019atelier a recommand\u00e9 entre autres la n\u00e9cessit\u00e9 de faire un plan d\u2019actions prenant en compte les aspects strat\u00e9giques et op\u00e9rationnel, la prise en compte des d\u00e9fis s\u00e9curitaires, du WASH d\u2019urgence (acc\u00e8s \u00e0 l\u2019eau et \u00e0 l\u2019assainissement des personnes d\u00e9plac\u00e9es internes), la s\u00e9curisation des ouvrages d\u2019AEP et des sources d\u2019eau.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/per_uemoa_togo_ok-1.jpg\" height=\"480\" width=\"640\"><\/p>","protected":false},"excerpt":{"rendered":"<p>La Commission de l\u2019Union Economique et Mon\u00e9taire Ouest Africaine (UEMOA) a organis\u00e9, du 25 au 27 octobre 2023, par visio conf\u00e9rence, l\u2019atelier de validation du rapport de l\u2019\u00e9tude prospective sur la mise en \u0153uvre des Objectifs de D\u00e9veloppement Durable (ODD) li\u00e9s \u00e0 l&#8217;eau et \u00e0 l&#8217;assainissement et \u00e0 la la Politique Commune d\u2019Am\u00e9lioration de l\u2019Environnement (PCAE).<\/p>","protected":false},"author":1,"featured_media":10919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":17,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/etude-prospective-sur-la-mise-en-uvre-des-odd-lies-a-leau-et-a-lassainissement-et-a-la-politique-commune-damelioration-de-lenvironnement-de-luemoa\/"],"_last_date":["field_69d4d498acab3"],"last_date":["08\/11\/2023"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10919"],"_edit_last":["1"],"iawp_total_views":["17"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/carte_uemoa_ok.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/carte_uemoa_ok-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/carte_uemoa_ok-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/carte_uemoa_ok-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/carte_uemoa_ok-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/carte_uemoa_ok.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/carte_uemoa_ok.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/carte_uemoa_ok-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"La Commission de l\u2019Union Economique et Mon\u00e9taire Ouest Africaine (UEMOA) a organis\u00e9, du 25 au 27 octobre 2023, par visio conf\u00e9rence, l\u2019atelier de validation du rapport de l\u2019\u00e9tude prospective sur la mise en \u0153uvre des Objectifs de D\u00e9veloppement Durable (ODD) li\u00e9s \u00e0 l'eau et \u00e0 l'assainissement et \u00e0 la la Politique Commune d\u2019Am\u00e9lioration de l\u2019Environnement\u2026","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/comments?post=6325"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6325\/revisions"}],"predecessor-version":[{"id":9628,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6325\/revisions\/9628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media\/10919"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media?parent=6325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/categories?post=6325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/tags?post=6325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}