{"id":6334,"date":"2023-09-28T00:00:00","date_gmt":"2023-09-27T23:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/gestion-durable-des-aquiferes-partages\/"},"modified":"2026-05-08T16:02:54","modified_gmt":"2026-05-08T15:02:54","slug":"gestion-durable-des-aquiferes-partages","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/news\/gestion-durable-des-aquiferes-partages\/","title":{"rendered":"Gestion durable des aquif\u00e8res partag\u00e9s"},"content":{"rendered":"<p>La Commission de l\u2019UEMOA organise en visioconf\u00e9rence, avec l\u2019appui du Partenariat Mondial de l\u2019Eau de l\u2019Afrique de l\u2019Ouest (GWP-AO) et d\u2019autres partenaires, un atelier r\u00e9gional sur la \u00ab <b><i>Gouvernance concert\u00e9e et la gestion durable des aquif\u00e8res partag\u00e9s<\/i><\/b> \u00bb. L\u2019\u00e9v\u00e8nement qui a d\u00e9marr\u00e9 le 28 septembre 2023 regroupe plus de cinquante (50) participants des pays membres de l\u2019UEMOA, des organismes de bassin, des organisations r\u00e9gionales ou internationales (OSS, GWH, CILSS, etc.), des personnes ressources.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/groupewhole-1.jpg\" height=\"300\" width=\"640\">&nbsp;Les besoins en eau de plus de la moiti\u00e9 de la population mondiale et d\u2019un grand nombre d\u2019activit\u00e9s socio\u00e9conomiques d\u00e9pendent des ressources en eau souterraines nationales et transfronti\u00e8res. Les pressions exerc\u00e9es sur les eaux souterraines sont de plus en plus importantes du fait des \u00e9volutions des modes de consommation, de l\u2019accroissement de la population mondiale et des besoins correspondants pour l\u2019agriculture, l\u2019alimentation en eau potable, l\u2019industrie, l\u2019\u00e9nergie, etc\u2026<\/p>\n<p>&nbsp;Les enjeux \u00e9conomiques, sociaux et environnementaux d\u2019une gouvernance concert\u00e9e et d\u2019une gestion rationnelle et raisonn\u00e9e des aquif\u00e8res partag\u00e9e sont consid\u00e9rables.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/online-1.jpg\" height=\"355\" width=\"640\">Prenant la parole \u00e0 la c\u00e9r\u00e9monie d\u2019ouverture, le Secr\u00e9taire Ex\u00e9cutif du GWP-AO, M. Armand HOUANYE a d\u00e9clar\u00e9 \u00ab&nbsp;<i>Le R\u00e9seau du GWP, compte tenu de sa niche d\u2019action, dispose d\u2019une expertise av\u00e9r\u00e9e dans tout ce qui touche \u00e0 la gestion int\u00e9gr\u00e9e et concert\u00e9e des ressources en eau, qu\u2019elles soient de surface ou souterraines. C\u2019est pourquoi, la tenue de cette rencontre constitue pour nous une bonne occasion pour accompagner la Commission de l\u2019UEMOA dans le partage d\u2019exp\u00e9rience avec tous les acteurs mondiaux, r\u00e9gionaux, transfrontaliers, nationaux et m\u00eame du niveau local<\/i>&nbsp;\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/presidium-2-1.jpg\" height=\"360\" width=\"640\">Cette initiative s\u2019inscrit dans le cadre de la mise en \u0153uvre de la Politique des Ressources en Eau de l\u2019Afrique de l\u2019Ouest (PREAO) et de la Politique Commune d\u2019Am\u00e9lioration de l\u2019Environnement (PCAE) et du Plan d\u2019Action de Gestion Int\u00e9gr\u00e9e des Ressources en Eau (GIRE) 2019-2030 dans l\u2019Espace UEMOA.<\/p>\n<p>Ce qui a fait dire \u00e0 M. Christophe DEGUENON, Directeur de l\u2019environnement et des ressources en eau parlant au nom de son commissaire, que \u00ab&nbsp;<i>le pr\u00e9sent atelier vise \u00e0 renforcer les capacit\u00e9s des acteurs des Etats membres et des Organismes de Bassin Transfrontaliers de l\u2019Union sur la gouvernance effective et la gestion durable des aquif\u00e8res partag\u00e9s et \u00e0 f\u00e9d\u00e9rer les efforts pour la mise en place de r\u00e9ponses appropri\u00e9es aux pr\u00e9occupations li\u00e9es \u00e0 la gouvernance effective et \u00e0 la gestion durable des aquif\u00e8res transfrontaliers. Pour rappel, cet atelier s\u2019inscrit dans le cadre la mise en \u0153uvre du Plan d\u2019actions GIRE de l\u2019UEMOA&nbsp;\u00bb<\/i>.<\/p>\n<p><b>&nbsp;<\/b>Ouverts le 28 septembre 2023 par le Commissaire Kako NUBUKPO, Commissaire charg\u00e9 du D\u00e9partement de l\u2019Agriculture et des Ressources en Eau repr\u00e9sent\u00e9 par son Directeur, les travaux de l\u2019atelier de deux jours prennent fin le 29 septembre 2023.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/room_ouaga-1.jpg\" height=\"360\" width=\"640\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Les Experts des Etats membres, des Organismes de Bassin Transfrontaliers et des Organisations r\u00e9gionales se concertent pour renforcer leurs capacit\u00e9s et d\u00e9finir les actions strat\u00e9giques et op\u00e9rationnelles \u00e0 mettre en place.<\/p>","protected":false},"author":1,"featured_media":10926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":4,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/gestion-durable-des-aquiferes-partages\/"],"_last_date":["field_69d4d498acab3"],"last_date":["28\/09\/2023"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10926"],"_edit_last":["1"],"iawp_total_views":["4"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/groupepic.jpg",1180,572,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/groupepic-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/groupepic-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/groupepic-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/groupepic-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/groupepic.jpg",1180,572,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/groupepic.jpg",1180,572,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/groupepic-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Les Experts des Etats membres, des Organismes de Bassin Transfrontaliers et des Organisations r\u00e9gionales se concertent pour renforcer leurs capacit\u00e9s et d\u00e9finir les actions strat\u00e9giques et op\u00e9rationnelles \u00e0 mettre en place.","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/comments?post=6334"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6334\/revisions"}],"predecessor-version":[{"id":9642,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/posts\/6334\/revisions\/9642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media\/10926"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/media?parent=6334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/categories?post=6334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/fr\/wp-json\/wp\/v2\/tags?post=6334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}