{"id":6227,"date":"2025-12-09T00:00:00","date_gmt":"2025-12-09T00:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/demarrage-de-latelier-regional-pour-la-validation-du-guide-methodologique-de-la-charte-de-leau-du-bassin-du-mono\/"},"modified":"2026-05-08T16:02:29","modified_gmt":"2026-05-08T15:02:29","slug":"demarrage-de-latelier-regional-pour-la-validation-du-guide-methodologique-de-la-charte-de-leau-du-bassin-du-mono","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/demarrage-de-latelier-regional-pour-la-validation-du-guide-methodologique-de-la-charte-de-leau-du-bassin-du-mono\/","title":{"rendered":"D\u00e9marrage de l\u2019atelier r\u00e9gional pour la validation du Guide m\u00e9thodologique de la Charte de l\u2019eau du bassin du Mono"},"content":{"rendered":"\n<p>Cet atelier marque une \u00e9tape cl\u00e9 dans la mise en \u0153uvre du <b>Projet IREE-Mono (2024-2028)<\/b>, financ\u00e9 par le Fonds pour l\u2019Environnement Mondial (FEM), qui vise \u00e0 renforcer la gouvernance et la coop\u00e9ration transfrontali\u00e8re entre le Togo et le B\u00e9nin pour une gestion durable des ressources en eau du bassin du Mono.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_guide_4-1.jpg\" height=\"364\" width=\"640\">Durant deux jours, les repr\u00e9sentants des administrations centrales, des collectivit\u00e9s locales, des institutions techniques, ainsi que des organisations de la soci\u00e9t\u00e9 civile des deux pays vont :<\/p>\n<ul>\n<li><b>Valider le rapport provisoire consolid\u00e9<\/b>, int\u00e9grant les contributions issues des ateliers nationaux tenus en septembre ;<\/li>\n<li><b>Amender et enrichir le Guide m\u00e9thodologique<\/b>, qui d\u00e9finit les \u00e9tapes cl\u00e9s pour la formulation et l\u2019application de la Charte de l\u2019eau ;<\/li>\n<li><b>Examiner la Note conceptuelle et le budget pr\u00e9visionnel<\/b> pour le d\u00e9ploiement de la phase d\u2019\u00e9laboration de la Charte.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_guide_2-1.jpg\" height=\"395\" width=\"640\">L\u2019atelier se d\u00e9roule dans une approche interactive, favorisant les \u00e9changes et la participation active des 35 acteurs cl\u00e9s du bassin, parmi lesquels des pr\u00e9fets, maires, minist\u00e8res sectoriels, l\u2019ABM, le GWP-AO et le consultant charg\u00e9 de la mission.<\/p>\n<p><b>Pourquoi cet atelier est important ?<\/b><br> La Charte de l\u2019eau du bassin du Mono est appel\u00e9e \u00e0 devenir un instrument strat\u00e9gique pour la pr\u00e9vention des conflits li\u00e9s \u00e0 l\u2019usage des ressources partag\u00e9es, la promotion de la coop\u00e9ration transfrontali\u00e8re et la gestion \u00e9quitable et durable des ressources en eau.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_guide_1-1.jpg\" height=\"407\" width=\"640\">La c\u00e9r\u00e9monie d\u2019ouverture a \u00e9t\u00e9 marqu\u00e9e par les allocutions du Pr\u00e9sident du Comit\u00e9 de Pilotage de l\u2019ABM, du Directeur Ex\u00e9cutif de l\u2019ABM et du repr\u00e9sentant du Minist\u00e8re en charge de l\u2019eau, soulignant l\u2019importance de cet outil pour la r\u00e9silience \u00e9cologique et le d\u00e9veloppement durable du bassin.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Autorit\u00e9 du Bassin du Mono (ABM), en partenariat avec l\u2019Observatoire du Sahara et du Sahel (OSS) et le Partenariat Mondial de l\u2019Eau en Afrique de l\u2019Ouest (GWP-AO), a lanc\u00e9 ce jour \u00e0 Lom\u00e9 l\u2019atelier r\u00e9gional de validation du rapport provisoire consolid\u00e9 de la mission de r\u00e9daction du Guide m\u00e9thodologique pour l\u2019\u00e9laboration et la mise en \u0153uvre de la Charte de l\u2019eau du bassin du Mono.<\/p>\n","protected":false},"author":1,"featured_media":10846,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":4,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/demarrage-de-latelier-regional-pour-la-validation-du-guide-methodologique-de-la-charte-de-leau-du-bassin-du-mono\/"],"_last_date":["field_69d4d498acab3"],"last_date":["09\/12\/2025"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10846"],"_edit_last":["1"],"iawp_total_views":["4"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_guide.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_guide-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_guide-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_guide-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_guide-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_guide.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_guide.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/iree_mono_guide-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"L\u2019Autorit\u00e9 du Bassin du Mono (ABM), en partenariat avec l\u2019Observatoire du Sahara et du Sahel (OSS) et le Partenariat Mondial de l\u2019Eau en Afrique de l\u2019Ouest (GWP-AO), a lanc\u00e9 ce jour \u00e0 Lom\u00e9 l\u2019atelier r\u00e9gional de validation du rapport provisoire consolid\u00e9 de la mission de r\u00e9daction du Guide m\u00e9thodologique pour l\u2019\u00e9laboration et la mise en&hellip;","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/comments?post=6227"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6227\/revisions"}],"predecessor-version":[{"id":9454,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6227\/revisions\/9454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media\/10846"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media?parent=6227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/categories?post=6227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/tags?post=6227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}