{"id":6291,"date":"2024-06-26T00:00:00","date_gmt":"2024-06-25T23:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/atelier-region-dappui-du-gwp-ao-a-lactualisation-de-la-strategie-de-communication-de-labv\/"},"modified":"2026-05-08T16:02:33","modified_gmt":"2026-05-08T15:02:33","slug":"atelier-region-dappui-du-gwp-ao-a-lactualisation-de-la-strategie-de-communication-de-labv","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/atelier-region-dappui-du-gwp-ao-a-lactualisation-de-la-strategie-de-communication-de-labv\/","title":{"rendered":"Atelier r\u00e9gion d\u2019appui du GWP-AO \u00e0 l\u2019actualisation de la Strat\u00e9gie de communication de l\u2019ABV"},"content":{"rendered":"\n<p>Un atelier technique restreint s\u2019est tenu du 19 au 24 f\u00e9vrier 2024 \u00e0 Koudougou, Burkina Faso. Il a permis d\u2019actualiser la Strat\u00e9gie de Communication de l\u2019ABV et son premier Plan d\u2019Action 2018-2020 en tenant compte des priorit\u00e9s de l\u2019ABV et de ses Etats membres en mati\u00e8re de gestion des ressources naturelles du bassin.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_hghtabe-1.jpg\" height=\"309\" width=\"640\">L\u2019atelier de deux jours qui a commenc\u00e9 ce 26 juin \u00e0 Accra au Ghana va permettre d\u2019amender et valider les projets de documents de strat\u00e9gie et de plan de communication issus des travaux de l\u2019atelier technique restreint en s\u2019assurant de sa coh\u00e9rence avec les documents strat\u00e9giques issus des r\u00e9cents projets de mise en \u0153uvre du PAS et en tenant compte des priorit\u00e9s de l\u2019ABV et de ses Etats membres.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_room_g-1.jpg\" height=\"480\" width=\"640\">Les participants \u00e0 l\u2019atelier r\u00e9gional&nbsp;d\u2019amendement et de validation des projets de Strat\u00e9gie pour la p\u00e9riode 2024 \u00e0 2030 et de Plan de communication 2024-2026 comprennent des Cadres de la Direction Ex\u00e9cutive de l\u2019ABV impliqu\u00e9s dans la mise en \u0153uvre du projet REWARD, des Cadres du Secr\u00e9tariat Ex\u00e9cutif du GWP-AO, des repr\u00e9sentants de chaque SFN\/ ABV, les responsables de communication des diff\u00e9rents minist\u00e8res de tutelles des 6 pays de l\u2019ABV, des membres du r\u00e9seau des journalistes de l\u2019ABV de chaque ainsi que de personnes ressources professionnels de la communication des pays membres.<\/p>\n<p>Les travaux de la rencontre se d\u00e9roule en pl\u00e9ni\u00e8res avec des travaux de groupes pour approfondir et enrichir les documents propos\u00e9s.&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_room-1.jpg\" height=\"296\" width=\"640\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019actualisation de la Strat\u00e9gie de Communication assortie du Plan d\u2019Action 2018-2020 de l\u2019Autorit\u00e9 du Bassin de la Volta (ABV), a \u00e9t\u00e9 int\u00e9gr\u00e9e dans le Plan de mise en \u0153uvre du Projet \u201cInverser les tendances de la D\u00e9gradation des Ecosyst\u00e8mes et des ressources en eaux dans le Bassin de la Volta (REWarD \u2013 Volta River Basin)\u2019\u2019, financ\u00e9 par le FEM et ex\u00e9cut\u00e9 par l\u2019ABV et le GWP-AO en \u00e9troite collaboration avec le PNUE et l\u2019UICN.<\/p>\n","protected":false},"author":1,"featured_media":10896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":9,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/atelier-region-dappui-du-gwp-ao-a-lactualisation-de-la-strategie-de-communication-de-labv\/"],"_last_date":["field_69d4d498acab3"],"last_date":["26\/06\/2024"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10896"],"_edit_last":["1"],"iawp_total_views":["9"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_group_strategy.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_group_strategy-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_group_strategy-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_group_strategy-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_group_strategy-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_group_strategy.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_group_strategy.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_group_strategy-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"L\u2019actualisation de la Strat\u00e9gie de Communication assortie du Plan d\u2019Action 2018-2020 de l\u2019Autorit\u00e9 du Bassin de la Volta (ABV), a \u00e9t\u00e9 int\u00e9gr\u00e9e dans le Plan de mise en \u0153uvre du Projet \u201cInverser les tendances de la D\u00e9gradation des Ecosyst\u00e8mes et des ressources en eaux dans le Bassin de la Volta (REWarD \u2013 Volta River Basin)\u2019\u2019,&hellip;","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/comments?post=6291"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6291\/revisions"}],"predecessor-version":[{"id":9569,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6291\/revisions\/9569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media\/10896"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media?parent=6291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/categories?post=6291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/tags?post=6291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}