{"id":6292,"date":"2024-06-24T00:00:00","date_gmt":"2024-06-23T23:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/projet-reward-atelier-pour-mieux-comprendre-lassistance-technique-du-pnue-dhi\/"},"modified":"2026-05-08T16:02:33","modified_gmt":"2026-05-08T15:02:33","slug":"projet-reward-atelier-pour-mieux-comprendre-lassistance-technique-du-pnue-dhi","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/projet-reward-atelier-pour-mieux-comprendre-lassistance-technique-du-pnue-dhi\/","title":{"rendered":"Projet REWarD, atelier pour mieux comprendre l\u2019assistance technique du PNUE DHI"},"content":{"rendered":"\n<p class=\"Intro\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_accra_ht-1.jpg\" height=\"296\" width=\"640\">L&#8217;ex\u00e9cution du travail de soutien technique par le PNUE-DHI pour atteindre ces r\u00e9sultats a commenc\u00e9 en d\u00e9cembre 2023 et se poursuivra pendant 3 ans jusqu&#8217;en 2026. Actuellement, le PNUE-DHI m\u00e8ne une phase de d\u00e9marrage de 6 mois pour rencontrer l&#8217;ABV et les partenaires, comprendre les exigences cl\u00e9s du projet et identifier les projets similaires ant\u00e9rieurs, en cours et pr\u00e9vus afin d&#8217;explorer les possibilit\u00e9s de synergies et d&#8217;\u00e9viter les doublons. \u00c0 la fin de la phase de d\u00e9marrage, le PNUE-DHI \u00e9laborera un plan de mise en \u0153uvre d\u00e9taill\u00e9 pour obtenir les r\u00e9sultats du projet.<\/p>\n<p class=\"Intro\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_accra_group-1.jpg\" height=\"296\" width=\"640\">Un atelier technique de deux jours les 24 et 25 juin 2024 se tient \u00e0 Accra au Ghana pour pr\u00e9senter et discuter le plan de mise en \u0153uvre d\u00e9taill\u00e9 de l&#8217;assistance technique qui sera fournie par le PNUE-DHI pour r\u00e9aliser les r\u00e9sultats dans le plan de mise en \u0153uvre du projet REWarD.<\/p>\n<p class=\"Intro\">L\u2019atelier r\u00e9uni les cadres de l\u2019ABV, du GWP-AO, des six pays membres de l\u2019ABV.<\/p>\n<p class=\"Intro\">&nbsp;<img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_accra_view-1.jpg\" height=\"296\" width=\"640\">Le PNUE et l&#8217;UICN, en collaboration avec l&#8217;ABV, le GWP-AO et les pays riverains du bassin du fleuve Volta, ont \u00e9labor\u00e9 au cours de la p\u00e9riode 2016-2021 le document de projet &#8220;Inverser la d\u00e9gradation des \u00e9cosyst\u00e8mes et de l&#8217;eau dans le bassin du fleuve Volta (REWarD &#8211; Bassin du fleuve Volta)&#8221;. L&#8217;objectif global du projet REWarD est d&#8217;inverser la d\u00e9gradation des \u00e9cosyst\u00e8mes et de l&#8217;eau et de soutenir le d\u00e9veloppement int\u00e9gr\u00e9 fond\u00e9 sur les \u00e9cosyst\u00e8mes dans le bassin du fleuve Volta gr\u00e2ce au renforcement de la gouvernance transfrontali\u00e8re et \u00e0 la restauration et la conservation des \u00e9cosyst\u00e8mes pour des moyens de subsistance durables.<\/p>\n<p class=\"Intro\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_accra_roompartial-1.jpg\" height=\"296\" width=\"640\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de la mise en \u0153uvre du Projet REWarD-Volta, le GWP-AO a sign\u00e9 avec le PNUE-DHI travaille en tant que sous-consultant pour fournir un soutien technique \u00e0 l\u2019ABV afin d&#8217;obtenir un certain nombre de r\u00e9sultats du projet REWarD dont des mod\u00e8les annuels de ressources en eau de surface et outils d&#8217;aide \u00e0 la d\u00e9cision, des syst\u00e8me(s) d&#8217;alerte pr\u00e9coce orient\u00e9(s) vers la communaut\u00e9 en cas de s\u00e9cheresse et l\u2019appui \u00e0 l&#8217;Observatoire du Bassin de la Volta afin qu\u2019il soit capable de g\u00e9rer et d&#8217;utiliser les mod\u00e8les actualis\u00e9s d&#8217;utilisation\/\u00e9quilibre de l&#8217;eau et l\u2019Outil d\u2019Aide \u00e0  la D\u00e9cision (OAD).<\/p>\n","protected":false},"author":1,"featured_media":10897,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":5,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/projet-reward-atelier-pour-mieux-comprendre-lassistance-technique-du-pnue-dhi\/"],"_last_date":["field_69d4d498acab3"],"last_date":["24\/06\/2024"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10897"],"_edit_last":["1"],"iawp_total_views":["5"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_accra.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_accra-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_accra-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_accra-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_accra-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_accra.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_accra.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/reward_accra-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Dans le cadre de la mise en \u0153uvre du Projet REWarD-Volta, le GWP-AO a sign\u00e9 avec le PNUE-DHI travaille en tant que sous-consultant pour fournir un soutien technique \u00e0 l\u2019ABV afin d'obtenir un certain nombre de r\u00e9sultats du projet REWarD dont des mod\u00e8les annuels de ressources en eau de surface et outils d'aide \u00e0 la&hellip;","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/comments?post=6292"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6292\/revisions"}],"predecessor-version":[{"id":9571,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6292\/revisions\/9571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media\/10897"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media?parent=6292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/categories?post=6292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/tags?post=6292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}