{"id":6303,"date":"2024-04-29T00:00:00","date_gmt":"2024-04-28T23:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/vfdm-le-ghana-organise-un-atelier-national-sur-lintegration-de-la-reduction-des-risques-de-catastrophes-et-ladaptation-au-changement-climatique\/"},"modified":"2026-05-08T16:02:33","modified_gmt":"2026-05-08T15:02:33","slug":"vfdm-le-ghana-organise-un-atelier-national-sur-lintegration-de-la-reduction-des-risques-de-catastrophes-et-ladaptation-au-changement-climatique","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/vfdm-le-ghana-organise-un-atelier-national-sur-lintegration-de-la-reduction-des-risques-de-catastrophes-et-ladaptation-au-changement-climatique\/","title":{"rendered":"VFDM, le Ghana organise un atelier national sur l&#8217;int\u00e9gration de la r\u00e9duction des risques de catastrophes et l&#8217;adaptation au changement climatique"},"content":{"rendered":"\n<p>Un consultant national et des enqu\u00eateurs ont men\u00e9 la \u00ab mission de renforcement des capacit\u00e9s politiques, institutionnelles et organisationnelles pour la gestion int\u00e9gr\u00e9e des risques d&#8217;inondation et de s\u00e9cheresse dans le bassin de la Volta au Ghana \u00bb. Ils ont proc\u00e9d\u00e9 \u00e0 une analyse documentaire, \u00e0 des visites de terrain et \u00e0 des entretiens avec les parties prenantes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana_pict-1.jpg\" height=\"304\" width=\"640\">L&#8217;atelier national a pour but d&#8217;am\u00e9liorer l&#8217;int\u00e9gration des politiques, des plans et des directives de RRC et d&#8217;ACC aux niveaux local, national et transfrontalier afin de renforcer la r\u00e9silience au changement climatique dans le bassin de la Volta.<\/p>\n<p>Les participants ont examin\u00e9 les politiques, plans et lignes directrices en mati\u00e8re de RRC et d&#8217;ACC, et fait des propositions d\u2019am\u00e9liorations pour renforcer leur int\u00e9gration et leur mise en \u0153uvre sur la base d&#8217;une coordination institutionnelle appropri\u00e9e et d&#8217;un m\u00e9canisme de collaboration aux niveaux local, national et transfrontalier dans la VB.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana_room-1.jpg\" height=\"360\" width=\"640\">Les participants comprennent la Commission des ressources en eau, les services m\u00e9t\u00e9orologiques du Ghana, le NADMO, les autorit\u00e9s locales du bassin, le Ghana Country Water Partnership, la Direction nationale charg\u00e9e de l&#8217;environnement, l&#8217;Agence nationale de l&#8217;environnement, le minist\u00e8re charg\u00e9 de la planification, le minist\u00e8re charg\u00e9 de l&#8217;agriculture, de l&#8217;\u00e9levage et de la p\u00eache, l&#8217;universit\u00e9 (Institut national de l&#8217;eau, WASCAL), les ONG.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana_max_mary-1.jpg\" height=\"311\" width=\"640\">S&#8217;exprimant lors de la c\u00e9r\u00e9monie d&#8217;ouverture au nom du consortium qui met en \u0153uvre le projet VFDM, M. Sidi COULIBALY du GWP-AO, a remerci\u00e9 toutes les parties prenantes ghan\u00e9ennes participant aux activit\u00e9s du projet aux niveaux local, national et r\u00e9gional. Il a indiqu\u00e9 que ces activit\u00e9s sont incluses dans le plan de travail du projet VFDM et se d\u00e9roulent dans les six pays de l&#8217;ABV avec des travaux de consultants qui ont conduit \u00e0 des ateliers locaux et nationaux dans chacun des pays du bassin de la Volta. Les r\u00e9sultats de ces ateliers seront \u00e9valu\u00e9s et contribueront \u00e0 l&#8217;atelier r\u00e9gional qui se tiendra les 13 et 14 juin dans la capitale togolaise, Lom\u00e9 dans la premi\u00e8re quinzaine de juin 2024.&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana_ht-1.jpg\" height=\"291\" width=\"640\">VFDM est financ\u00e9 par le Fonds d&#8217;adaptation et mis en \u0153uvre par l&#8217;OMM, l&#8217;ABV et le GWP-AO.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana_group-1.jpg\" height=\"288\" width=\"640\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les parties prenantes au Ghana ont organis\u00e9 les 29 et 30 avril 2024 un atelier national pour examiner l&#8217;int\u00e9gration de la r\u00e9duction des risques de catastrophe (RRC) et l&#8217;adaptation au changement climatique (ACC) politiques, plans et lignes directrices aux niveaux local, national et transfrontalier dans le bassin de la Volta.<\/p>\n","protected":false},"author":1,"featured_media":10904,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":5,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/vfdm-le-ghana-organise-un-atelier-national-sur-lintegration-de-la-reduction-des-risques-de-catastrophes-et-ladaptation-au-changement-climatique\/"],"_last_date":["field_69d4d498acab3"],"last_date":["29\/04\/2024"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10904"],"_edit_last":["1"],"iawp_total_views":["5"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/vfdm_ghana-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Les parties prenantes au Ghana ont organis\u00e9 les 29 et 30 avril 2024 un atelier national pour examiner l'int\u00e9gration de la r\u00e9duction des risques de catastrophe (RRC) et l'adaptation au changement climatique (ACC) politiques, plans et lignes directrices aux niveaux local, national et transfrontalier dans le bassin de la Volta.","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/comments?post=6303"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6303\/revisions"}],"predecessor-version":[{"id":9588,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6303\/revisions\/9588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media\/10904"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media?parent=6303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/categories?post=6303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/tags?post=6303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}