{"id":6308,"date":"2024-04-22T00:00:00","date_gmt":"2024-04-21T23:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/4eme-edition-du-forum-national-de-leau-et-de-lassainissement-du-burkina-faso\/"},"modified":"2026-05-08T16:02:33","modified_gmt":"2026-05-08T15:02:33","slug":"4eme-edition-du-forum-national-de-leau-et-de-lassainissement-du-burkina-faso","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/4eme-edition-du-forum-national-de-leau-et-de-lassainissement-du-burkina-faso\/","title":{"rendered":"4\u00e8me \u00e9dition du Forum National de l\u2019Eau et de l\u2019Assainissement du Burkina Faso"},"content":{"rendered":"\n<p>Le Forum National de l\u2019Eau et de l\u2019Assainissement (FNEA) vise \u00e0 assurer la mobilisation citoyenne et populaire ainsi que le dialogue multi-acteurs autour des enjeux de l\u2019eau et de l\u2019assainissement. Les parties prenantes (professionnels, d\u00e9cideurs, usagers et citoyens) ont ainsi l\u2019opportunit\u00e9 de discuter et de partager les probl\u00e8mes, les solutions et les priorit\u00e9s, de prendre des engagements forts (selon les diff\u00e9rentes cat\u00e9gories et responsabilit\u00e9s sp\u00e9cifiques), de d\u00e9finir des messages et positions clairs \u00e0 d\u00e9fendre au sein de la communaut\u00e9 internationale de l\u2019eau et de l\u2019assainissement.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/forum-national-1.jpg\" height=\"360\" width=\"640\">Plac\u00e9e sous le haut patronage du Pr\u00e9sident de la Transition, Chef de l\u2019Etat repr\u00e9sent\u00e9 par le Ministre d\u2019Etat en charge de la Communication, de la culture, des arts et du tourisme, porte-parole du gouvernement, cette \u00e9dition a \u00e9t\u00e9 ouverte ce 22 avril dans la Salle de Conf\u00e9rences de Ouaga 2000.<\/p>\n<p>Le 4\u00e8me forum national de l\u2019eau et de l\u2019assainissement s\u2019articule autour de conf\u00e9rences-d\u00e9bats (sessions pl\u00e9ni\u00e8res et th\u00e9matiques) et de manifestations publiques (manifestation sportive, sc\u00e8ne artistique, une foire d\u2019exposition o\u00f9 seront expos\u00e9es des initiatives et des projets exemplaires et une nuit de remise des troph\u00e9es). Il r\u00e9unit plusieurs centaines de participants provenant des structures \u00e9tatiques (autorit\u00e9s gouvernementales, autorit\u00e9s parlementaires, services techniques centraux et d\u00e9concentr\u00e9s), des collectivit\u00e9s locales, du secteur priv\u00e9, de la soci\u00e9t\u00e9 civile, des Agences de l\u2019Eau, des partenaires techniques et financiers intervenant dans le secteur de l\u2019eau et l\u2019assainissement, des usagers des services d\u2019eau et d\u2019assainissement, etc.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/fnea-1.jpg\" height=\"303\" width=\"640\">GWP-AO est un partenaire technique qui apporte un appui technique et financier dans le cadre de l\u2019organisation de la pr\u00e9sente \u00e9dition \u00e0 travers notamment la participation aux travaux de commissions, \u00e0 l\u2019animation de session et un appui financier pour accompagner l\u2019organisation g\u00e9n\u00e9rale et la tenue de la nuit des troph\u00e9es.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/forumnational-1.jpg\" height=\"303\" width=\"640\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Minist\u00e8re de l\u2019Environnement, de l\u2019Eau et de l\u2019Assainissement, organise du 22 au 24 avril 2024 le 4\u00e8me forum national de l\u2019Eau et de l\u2019Assainissement sous le th\u00e8me \u00ab Eau : Facteur de R\u00e9silience, de Paix et de D\u00e9veloppement \u00bb.<\/p>\n","protected":false},"author":1,"featured_media":10908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":7,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/4eme-edition-du-forum-national-de-leau-et-de-lassainissement-du-burkina-faso\/"],"_last_date":["field_69d4d498acab3"],"last_date":["22\/04\/2024"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10908"],"_edit_last":["1"],"iawp_total_views":["7"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/fnea4.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/fnea4-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/fnea4-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/fnea4-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/fnea4-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/fnea4.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/fnea4.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/fnea4-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Le Minist\u00e8re de l\u2019Environnement, de l\u2019Eau et de l\u2019Assainissement, organise du 22 au 24 avril 2024 le 4\u00e8me forum national de l\u2019Eau et de l\u2019Assainissement sous le th\u00e8me \u00ab Eau : Facteur de R\u00e9silience, de Paix et de D\u00e9veloppement \u00bb.","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/comments?post=6308"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6308\/revisions"}],"predecessor-version":[{"id":9599,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6308\/revisions\/9599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media\/10908"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media?parent=6308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/categories?post=6308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/tags?post=6308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}