{"id":6344,"date":"2023-05-23T00:00:00","date_gmt":"2023-05-22T23:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/tonfuturtonclimat-pour-faire-des-jeunes-des-acteurs-cles-pour-la-securite-en-eau-et-la-resilience-climatique-au-niveau-local\/"},"modified":"2026-05-08T16:02:55","modified_gmt":"2026-05-08T15:02:55","slug":"tonfuturtonclimat-pour-faire-des-jeunes-des-acteurs-cles-pour-la-securite-en-eau-et-la-resilience-climatique-au-niveau-local","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/tonfuturtonclimat-pour-faire-des-jeunes-des-acteurs-cles-pour-la-securite-en-eau-et-la-resilience-climatique-au-niveau-local\/","title":{"rendered":"Tonfuturtonclimat, pour faire des jeunes, des acteurs cl\u00e9s pour la s\u00e9curit\u00e9 en eau et la r\u00e9silience climatique au niveau local"},"content":{"rendered":"\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/forage_tftc_burkina-1.jpg\" height=\"281\" width=\"640\">C\u2019est la conviction de M. Maxime TEBLEKOU, Charg\u00e9 r\u00e9gional du projet TonFuturTonClimat phase 2 ou TFTC 2 au Global Water Partnership en Afrique de l\u2019Ouest (GWP-AO). TFTC 2 est construit sur l&#8217;exp\u00e9rience et les r\u00e9sultats de TFTC 1 2017 \u2013 2020. Il est bas\u00e9 sur la mise en \u0153uvre de trois (3) initiatives nationales que sont&nbsp;: (i) le projet de \u00ab&nbsp;Mobilisation des associations de jeunes pour une meilleure gestion des ressources en eau du micro-bassin de Tchoutchoubou dans le bassin de la Pendjari&nbsp;\u00bb au B\u00e9nin&nbsp;; (ii) le projet de \u00ab&nbsp;Promotion de bonnes pratiques en mati\u00e8re de gestion durable des terres, d\u2019adaptation aux changements climatiques et de conservation de la diversit\u00e9 biologique dans la commune rurale de Komki Ipala&nbsp;\u00bb au Burkina Faso&nbsp;; et (iii) le projet d\u2019\u00ab&nbsp;Appui des jeunes pour une transition vers une agriculture durable \u00e0 travers des pratiques agro \u00e9cologiques dans les communes du Grand Kloto&nbsp;\u00bb au Togo.<\/p>\n<p>Ces initiatives mod\u00e8les durables, \u00e9conomiquement viables, r\u00e9plicables et \u00e0 impacts tangibles pour les populations ont mis en avant des jeunes leaders des milieux ruraux et p\u00e9ri-urbains dans leur conception, leur planification et leur mise en \u0153uvre. Le projet a permis de renforcer les capacit\u00e9s des associations et \u00e0 outiller les jeunes (18-35 ans) du B\u00e9nin du Burkina Faso et du Togo \u00e0 devenir promoteurs d&#8217;id\u00e9es novatrices pour r\u00e9pondre durablement aux enjeux li\u00e9s aux changements climatiques et soutenir le d\u00e9veloppement \u00e9conomique local.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/compostage_liquide_tftc_benin-1.jpg\" height=\"480\" width=\"640\">TFTC 2 a permis de renforcer les capacit\u00e9s de plus 530 jeunes (filles et gar\u00e7ons) dans les trois pays b\u00e9n\u00e9ficiaires dans diff\u00e9rents domaines d\u2019activit\u00e9s socio-\u00e9conomiques dont la fabrication de compost, la r\u00e9alisation de foyers am\u00e9lior\u00e9s, la mise en place de p\u00e9pini\u00e8re, l\u2019application de techniques agricoles \u00e9cologiques, la protection de l\u2019environnement, l\u2019am\u00e9nagement et la restauration de sols d\u00e9grad\u00e9s, la protection de sols et des berges, la bonne structuration d\u2019une association, la bonne tenue de documents comptables, l\u2019\u00e9laboration de petits projets, la commercialisations de produits agricoles notamment. TFTC 2 a en outre permis de donner de la visibilit\u00e9 et de la voix aux associations de jeunes aupr\u00e8s des autorit\u00e9s locales d\u2019une part&nbsp;; et d\u2019autre part faciliter leur implication dans les cercles de prise de d\u00e9cisions en mati\u00e8re de gestion des probl\u00e8mes li\u00e9s \u00e0 l\u2019eau et des impacts des changements climatiques au niveau local.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/room_tftc_lome-1.jpg\" height=\"360\" width=\"640\">Ce qui a fait dire \u00e0 Mme Laurie FOURNEAUX, Charg\u00e9e de programme jeunesse au Secr\u00e9tariat International de l\u2019Eau (SIE) qu\u2019en \u00ab&nbsp;m<i>ettant en avant des strat\u00e9gies et solutions hydriques \u00e0 la fois novatrices et ancr\u00e9es dans le d\u00e9veloppement local de leurs communaut\u00e9s, les jeunes, soutenus par le projet TonFuturTonClimat, ont d\u00e9montr\u00e9 leurs capacit\u00e9s \u00e0 \u00eatre une force de changement pour garantir un meilleur futur \u00e0 tous et \u00e0 toutes dans cette \u00e8re incertaine perturb\u00e9e par le changement climatique. En soutenant ces laboratoires sociaux, \u00e9conomiques et environnementaux aux B\u00e9nin, Burkina Faso et Togo, le Secr\u00e9tariat International de l\u2019Eau souhaite mettre en lumi\u00e8re le potentiel transformateur des jeunes encore largement sous exploit\u00e9 et que les r\u00e9sultats obtenus fassent boules de neige aux niveaux national&nbsp;et&nbsp;r\u00e9gional<\/i>&nbsp;\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/planche_tftc_burkina-1.jpg\" height=\"281\" width=\"640\">Lanc\u00e9e en mai 2021 \u00e0 Ouagadougou au Burkina Faso, la mise en \u0153uvre de TFTC 2 a pris fin en avril 2023 apr\u00e8s 2 ans d\u2019ex\u00e9cution des activit\u00e9s. Pour tirer les le\u00e7ons apprises de la mise en \u0153uvre et formuler des recommandations pour une mise \u00e0 l\u2019\u00e9chelle des r\u00e9sultats en Afrique de l\u2019Ouest, les acteurs de mise en \u0153uvre du projet TFTC2 se retrouvent dans le cadre d\u2019un atelier de cl\u00f4ture du 23 au 26 mai 2023 \u00e0 Lom\u00e9 au Togo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/tftc_burkina-1-1.jpg\" height=\"281\" width=\"640\">C\u2019est en r\u00e9ponse \u00e0 l\u2019appel du Programme de Coop\u00e9ration Climatique Internationale (PCCI) que le Secr\u00e9tariat International de l\u2019Eau (SIE) et le Partenariat Mondial de l\u2019Eau en Afrique de l\u2019Ouest (GWP-AO), ont soumis et obtenu le financement pour la mise en \u0153uvre de la Phase 2 de l\u2019initiative TonFuturTonClimat (TFTC 2) en collaboration avec le Partenariat National de l\u2019Eau du B\u00e9nin (PNE-B\u00e9nin), le Partenariat National de l\u2019Eau du Burkina Faso (PNE-Burkina) et l\u2019ONG Jeunes Volontaires pour l\u2019Environnement du Togo (JVE Togo). Le projet TFTC2 est financ\u00e9 par le Gouvernement du Qu\u00e9bec et le Partenariat Mondial de l\u2019Eau (GWP), la Direction du D\u00e9veloppement et de la Coop\u00e9ration (DDC) et l\u2019Agence de l\u2019Eau Artois Picardie.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/arrosage_tftc_benin-1.jpg\" height=\"853\" width=\"640\">Dans tous les trois pays, les b\u00e9n\u00e9ficiaires sont unanimes \u00e0 reconnaitre l\u2019incidence du projet sur leur vie comme en t\u00e9moigne Mlle BEKOUANA Drusile,&nbsp;jeune fille b\u00e9n\u00e9ficiaire du projet TFTC 2, tr\u00e9sori\u00e8re de la Coop\u00e9rative \u00ab&nbsp;Bio Or Dur&nbsp;\u00bb de Tangui\u00e9ta au B\u00e9nin&nbsp;: \u00ab <i>Je suis tr\u00e8s heureuse d\u2019appartenir \u00e0 un groupe de jeunes qui travaillent \u00e0 s\u2019autonomiser et \u00e0 cr\u00e9er de l\u2019emploi autour de la production des fertilisants organiques, et cela avec l\u2019appui du projet TFTC2<\/i>&nbsp;\u00bb.Au Burkina Faso, Mme LOURGO Marcelline, promotrice de foyers am\u00e9lior\u00e9s dans le village de Vipalgo d\u00e9clare \u00ab&nbsp;<i>Nous avons \u00e9t\u00e9 form\u00e9es dans le cadre du projet TFTC2 sur les techniques de fabrication de foyers am\u00e9lior\u00e9s \u00e0 base d\u2019argile.&nbsp; Cette formation nous a appris un nouveau m\u00e9tier, qui pourra am\u00e9liorer notre cadre de vie<\/i>&nbsp;\u00bb. Quant \u00e0 M. BATCHEY Komlan Ap\u00e9doh, Maire de Kp\u00e9l\u00e9 1 au Togo, il conclut en ces termes&nbsp;: \u00ab&nbsp;<i>Le projet, moi je l\u2019ai adopt\u00e9 car il nous a permis de reboiser 7 ha de plants forestiers de Gm\u00e9lina, de Neem et d\u2019Acacia. J\u2019ai aussi adopt\u00e9 l\u2019agro\u00e9cologie, dont je fais la promotion et je me nourris des produits issus de l\u2019agro\u00e9cologie car cette agriculture<\/i>&nbsp;<i>soigne <\/i>\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/salle_dos_tftc_lome-1.jpg\" height=\"389\" width=\"640\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Les jeunes constituent une force tr\u00e8s importante aussi bien pour le d\u00e9veloppement durable que pour la gestion rationnelle des ressources en eau. Dans la sous-r\u00e9gion ouest africaine, cette force est tr\u00e8s sous utilis\u00e9e. GWP travaille donc avec les organisations aux niveaux r\u00e9gional et sous r\u00e9gional ainsi que les mouvements de jeunes pour faire entendre leur voix afin qu\u2019ils soient davantage impliqu\u00e9s et de fa\u00e7on soutenue dans les processus de prise de d\u00e9cisions du secteur de l\u2019eau, dans la mise en \u0153uvre de l\u2019accord de Paris sur le climat, de l\u2019ODD #6 dans la r\u00e9gion ouest africaine. Les jeunes \u00e9tant la rel\u00e8ve de demain, on ne peut ou ne devrait rien faire sans les jeunes \u00bb.<\/p>\n","protected":false},"author":1,"featured_media":10934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":18,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":["<div><div><article class=\"c-module\">\n        <div class=\"c-module__header\">\n            <h1 class=\"c-module__heading\">Fiche de capitalisation du projet TFTC 2<\/h1>\n        <\/div>\n        <div class=\"c-module__content c-module__content--padded\">\n        <div class=\"s-cms-module-content\">\n            <p><a href=\"https:\/\/gwpo-gwp.org\/assets\/legacy\/globalassets\/global\/gwp-waf_files\/tftc_mai_2023\/fiche_tftc_2_18_5_2023_finale.pdf\">Fiche de capitalisation du projet TFTC 2<\/a><\/p>\n        <\/div>\n    <\/div>\n<\/article><\/div><div><article class=\"c-module\">\n        <div class=\"c-module__header\">\n            <h1 class=\"c-module__heading\">Film de capitalisation de TFTC 2<\/h1>\n        <\/div>\n        <div class=\"c-module__content c-module__content--padded\">\n        <div class=\"s-cms-module-content\">\n            <p><iframe src=\"https:\/\/www.youtube.com\/embed\/ULKtaBBtOQ0\" frameborder=\"0\" width=\"300\" height=\"247\" data-gtm-yt-inspected-9=\"true\"><\/iframe><\/p>\n        <\/div>\n    <\/div>\n<\/article><\/div><div><article class=\"c-module\">\n        <div class=\"c-module__header\">\n            <h1 class=\"c-module__heading\">Principales r\u00e9alisations du projet<\/h1>\n        <\/div>\n        <div class=\"c-module__content c-module__content--padded\">\n        <div class=\"s-cms-module-content\">\n            <p><a href=\"https:\/\/gwpo-gwp.org\/assets\/legacy\/globalassets\/global\/gwp-waf_files\/tftc_mai_2023\/acquis-du-projet_presentation-generale.pdf\">Presentation des principales r\u00e9alisations du projet<\/a><\/p>\n        <\/div>\n    <\/div>\n<\/article><\/div><div><article class=\"c-module\">\n        <div class=\"c-module__header\">\n            <h1 class=\"c-module__heading\">Appel aux partenaires<\/h1>\n        <\/div>\n        <div class=\"c-module__content c-module__content--padded\">\n        <div class=\"s-cms-module-content\">\n            <p><a href=\"https:\/\/gwpo-gwp.org\/assets\/legacy\/globalassets\/global\/gwp-waf_files\/tftc_mai_2023\/adresse-aux-partenaires-pour-plus-d_action-vers-les-jeunes.pdf\">Appel aux partenaires<\/a><\/p>\n        <\/div>\n    <\/div>\n<\/article><\/div><div>\n<article class=\"c-module\">\n    <div class=\"c-module__header\">\n        <h1 class=\"c-module__heading\">TFTC 2 dans la presse au Togo<\/h1>\n    <\/div>\n    <div class=\"c-module__content c-module__content--padded\">\n<ul class=\"c-link-list c-link-list--expandable\">\n        <li class=\"c-link-list__item c-link-list__item--icon\"><a href=\"https:\/\/letabloid.tg\/eau-et-resilience-climatique-les-acteurs-du-projet-tonfuturtonclimat-au-bilan-de-la-phase-2-a-lome\/\" title=\"Le Tablo\u00efd\">Le Tablo\u00efd<\/a><\/li>\n        <li class=\"c-link-list__item c-link-list__item--icon\"><a href=\"https:\/\/vitrinenews.tg\/2023\/05\/23\/resilience-aux-changements-climatiques-le-projet-tonfuturtonclimat-est-a-letape-du-bilan\/\" title=\"Vitrine News\">Vitrine News<\/a><\/li>\n        <li class=\"c-link-list__item c-link-list__item--icon\"><a href=\"https:\/\/togoenlive.info\/2023\/05\/23\/projet-ton-futur-ton-climat-2-les-acteurs-de-mise-en-oeuvre-en-atelier-de-bilan-a-lome\/\" title=\"Togo en Live\">Togo en Live<\/a><\/li>\n        <li class=\"c-link-list__item c-link-list__item--icon\"><a href=\"https:\/\/vert-togo.tg\/que-retenir-du-projet-tonfuturtonclimat\/\" title=\"Vert Togo\">Vert Togo<\/a><\/li>\n        <li class=\"c-link-list__item c-link-list__item--icon\"><a href=\"https:\/\/www.societecivilemedias.com\/2023\/05\/24\/fin-du-projet-tonfuturtonclimat-phase-2-les-acteurs-impliques-font-leur-bilan-a-lome\/\" title=\"Soci\u00e9t\u00e9 Civile Media\">Soci\u00e9t\u00e9 Civile Media<\/a><\/li>\n        <li class=\"c-link-list__item c-link-list__item--icon\"><a href=\"https:\/\/www.plumedafrique.tg\/afrique-de-louest\/togo-projet-ton-futur-ton-climat2-apres-deux-ans-de-mise-en-oeuvre-place-au-bilan\/\" title=\"Plume d'Afrique\">Plume d'Afrique<\/a><\/li>\n        <li class=\"c-link-list__item c-link-list__item--icon\"><a href=\"https:\/\/lomebougeinfo.tg\/deuxieme-phase-dexecution-du-projet-tonfuturtonclimat-lheure-du-bilan-et-des-perspectives\/\" title=\"Lom\u00e9 bongue Info\">Lom\u00e9 bouge Info<\/a><\/li>\n        <li class=\"c-link-list__item c-link-list__item--icon\"><a href=\"https:\/\/vert-togo.tg\/la-2eme-phase-du-projet-ton-futur-ton-climat-change-les-pratiques-agricoles-de-plus-de-530-jeunes-africains\/\" title=\"Vert Togo\">Vert Togo<\/a><\/li>\n        <li class=\"c-link-list__item c-link-list__item--icon\"><a href=\"https:\/\/globalactu.com\/2023\/05\/27\/togo-cloture-de-tftc-2-une-satisfaction-generale-se-degage-a-lome\/\" title=\"Global Actu\">Global Actu<\/a><\/li>\n<\/ul>\n\n            <a href=\"#\" class=\"c-button c-button--stretch c-button--small\">Show all links<\/a>\n    <\/div>\n<\/article><\/div><\/div>"],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/tonfuturtonclimat-pour-faire-des-jeunes-des-acteurs-cles-pour-la-securite-en-eau-et-la-resilience-climatique-au-niveau-local\/"],"_last_date":["field_69d4d498acab3"],"last_date":["23\/05\/2023"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["10934"],"_edit_last":["1"],"iawp_total_views":["18"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/group_tftc_lome.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/group_tftc_lome-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/group_tftc_lome-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/group_tftc_lome-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/group_tftc_lome-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/group_tftc_lome.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/group_tftc_lome.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/group_tftc_lome-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00ab Les jeunes constituent une force tr\u00e8s importante aussi bien pour le d\u00e9veloppement durable que pour la gestion rationnelle des ressources en eau. Dans la sous-r\u00e9gion ouest africaine, cette force est tr\u00e8s sous utilis\u00e9e. GWP travaille donc avec les organisations aux niveaux r\u00e9gional et sous r\u00e9gional ainsi que les mouvements de jeunes pour faire entendre&hellip;","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/comments?post=6344"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6344\/revisions"}],"predecessor-version":[{"id":9661,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6344\/revisions\/9661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media\/10934"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media?parent=6344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/categories?post=6344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/tags?post=6344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}