{"id":6446,"date":"2022-06-09T00:00:00","date_gmt":"2022-06-08T23:00:00","guid":{"rendered":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/collaboration-avec-linstitut-national-de-leau-du-benin-sur-le-partage-des-connaissances\/"},"modified":"2026-05-08T16:03:39","modified_gmt":"2026-05-08T15:03:39","slug":"collaboration-avec-linstitut-national-de-leau-du-benin-sur-le-partage-des-connaissances","status":"publish","type":"post","link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/news\/collaboration-avec-linstitut-national-de-leau-du-benin-sur-le-partage-des-connaissances\/","title":{"rendered":"Collaboration avec l&#8217;Institut National de l&#8217;Eau du B\u00e9nin sur le partage des connaissances"},"content":{"rendered":"\n<p>&#8211; Webinaire 1 : la gouvernance de l&#8217;eau au Sahel (B\u00e9nin, Burkina Faso, Mali et Niger) ;<\/p>\n<p>&#8211; Webinaire 2 : Planification de la gestion des ressources en eau au Sahel (B\u00e9nin, Burkina Faso, Mali et Niger) ;<\/p>\n<p>&#8211; Webinar 3 : Hydro-diplomatie et moyens de r\u00e9solution des conflits autour de la ressource au Sahel.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/benin_in-1.jpg\" height=\"480\" width=\"640\">GWP-AO a accept\u00e9 de soutenir une telle dynamique en mobilisant des intervenants et des personnes ressources tels que : (i) M. Bourama TRAOR\u00c9 du Mali et Prof. SANDAO Issoufou le Secr\u00e9taire Permanent du PANGIRE du Niger pour le Webinar 1 ; (ii) M. CONGO Moustapha le Secr\u00e9taire Permanent de la GIRE du Burkina Faso et Prof. SANDAO Issoufou le Secr\u00e9taire Permanent du PANGIRE du Niger pour le Webinar 2 ; et (iii) M. Armand HOUANYE Secr\u00e9taire Ex\u00e9cutif de GWP-AO pour le Webinar 3.<\/p>\n<p>GWP-AO a contribu\u00e9 au cadrage technique du contenu et \u00e0 la coh\u00e9rence entre les \u00e9l\u00e9ments (aspects th\u00e9oriques et \u00e9tudes de cas) de chacun des 3 webinaires en prenant part \u00e0 des r\u00e9unions de pr\u00e9paration en ligne ainsi qu&#8217;\u00e0 la fourniture de supports techniques. GWP a \u00e9galement assur\u00e9 la participation effective des personnes ressources au webinaire 1 le 2 mai 2022 de 11h30 \u00e0 13h00 GMT, au webinaire 2 le 9 mai 2022 de 11h30 \u00e0 13h00 GMT et au webinaire 3 le 16 mai 2022 de 11h30 \u00e0 13h00 GMT.<\/p>\n<p>Les enseignants de l&#8217;INE sont tr\u00e8s satisfaits de cette collaboration et ont propos\u00e9 de la formaliser tr\u00e8s prochainement avec le GWP-AO afin de travailler ensemble sur de nouveaux projets et de b\u00e9n\u00e9ficier de l&#8217;expertise du GWP et de son r\u00e9seau d&#8217;experts, de personnes ressources et de partenaires.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/beninine-1.jpg\" height=\"480\" width=\"640\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la fin du mois d&#8217;avril 2022, le secr\u00e9tariat du GWP-AO a \u00e9t\u00e9 approch\u00e9 par le PNE B\u00e9nin avec une demande de collaboration de l&#8217;Institut National de l&#8217;Eau du B\u00e9nin pour mobiliser des personnes ressources dans la r\u00e9gion afin de fournir un contenu appropri\u00e9 et de conduire 3 webinaires sur :<\/p>\n","protected":false},"author":1,"featured_media":11017,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":4,"footnotes":""},"categories":[60,76,4],"tags":[99],"class_list":["post-6446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archive","category-french","category-news","tag-afrique-de-louest"],"acf":[],"spectra_custom_meta":{"_sidebar_content":["field_69d4d421acab1"],"sidebar_content":[""],"_old_url":["field_69d4d472acab2"],"old_url":["https:\/\/www.gwp.org\/fr\/GWP-Afrique-Ouest\/GWP-in-Action\/News--Activities\/collaboration-avec-linstitut-national-de-leau-du-benin-sur-le-partage-des-connaissances\/"],"_last_date":["field_69d4d498acab3"],"last_date":["09\/06\/2022"],"_event_start":["field_69d4d4c4acab4"],"event_start":[""],"_event_end":["field_69d4d4dcacab5"],"event_end":[""],"_scrape_id":["field_69d4d4ebacab6"],"scrape_id":["05-GWP-French-West-Africa"],"_wp_page_template":["default"],"_thumbnail_id":["11017"],"_edit_last":["1"],"iawp_total_views":["4"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:13:\"core\/freeform\";i:1;s:11:\"core\/search\";i:2;s:10:\"core\/group\";i:3;s:12:\"core\/heading\";i:4;s:20:\"core\/latest-comments\";i:5;s:9:\"core\/list\";i:6;s:14:\"core\/list-item\";i:7;s:19:\"rank-math\/toc-block\";i:8;s:14:\"core\/accordion\";i:9;s:19:\"core\/accordion-item\";i:10;s:22:\"core\/accordion-heading\";i:11;s:20:\"core\/accordion-panel\";i:12;s:14:\"core\/paragraph\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1787820039\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/benin_ine.jpg",1180,571,false],"thumbnail":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/benin_ine-150x150.jpg",150,150,true],"medium":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/benin_ine-300x145.jpg",300,145,true],"medium_large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/benin_ine-768x372.jpg",768,372,true],"large":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/benin_ine-1024x496.jpg",1024,496,true],"1536x1536":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/benin_ine.jpg",1180,571,false],"2048x2048":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/benin_ine.jpg",1180,571,false],"trp-custom-language-flag":["https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-content\/uploads\/sites\/17\/2026\/04\/benin_ine-18x9.jpg",18,9,true]},"uagb_author_info":{"display_name":"satsiriwinberg@gmail.com","author_link":"https:\/\/gwpo-gwp.org\/afrique-ouest\/author\/satsiriwinberggmail-com\/"},"uagb_comment_info":0,"uagb_excerpt":"A la fin du mois d'avril 2022, le secr\u00e9tariat du GWP-AO a \u00e9t\u00e9 approch\u00e9 par le PNE B\u00e9nin avec une demande de collaboration de l'Institut National de l'Eau du B\u00e9nin pour mobiliser des personnes ressources dans la r\u00e9gion afin de fournir un contenu appropri\u00e9 et de conduire 3 webinaires sur :","_links":{"self":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/comments?post=6446"}],"version-history":[{"count":2,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6446\/revisions"}],"predecessor-version":[{"id":9824,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/posts\/6446\/revisions\/9824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media\/11017"}],"wp:attachment":[{"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/media?parent=6446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/categories?post=6446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gwpo-gwp.org\/afrique-ouest\/wp-json\/wp\/v2\/tags?post=6446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}